{"id":10052,"date":"2019-08-29T00:02:00","date_gmt":"2019-08-28T22:02:00","guid":{"rendered":"https:\/\/borncity.com\/senioren\/?p=10052"},"modified":"2024-10-03T00:20:58","modified_gmt":"2024-10-02T22:20:58","slug":"aufblasbare-weltraum-habitate-im-kommen","status":"publish","type":"post","link":"https:\/\/borncity.eu\/senioren\/2019\/08\/29\/aufblasbare-weltraum-habitate-im-kommen\/","title":{"rendered":"Aufblasbare Weltraum-Habitate im Kommen"},"content":{"rendered":"<p>In den USA hat eine Firma gerade ausblasbare Weltraum-Aufenthaltsmodule vorgestellt. Diese k\u00f6nnten sp\u00e4ter f\u00fcr den Flug zu Mond oder den Mars dienen, bieten sie den Raumfahrern doch mehr Platz als heutige Raumkapseln. Vor allem sind die Module leicht und lassen sich mit heutigen Raketen zum Mond transportieren.<\/p>\n<p><!--more--><\/p>\n<p>Mir war das Konzept der aufblasbaren Weltraum-Aufenthaltsmodule von der Firma <a href=\"https:\/\/de.wikipedia.org\/wiki\/Bigelow_Aerospace\" target=\"_blank\" rel=\"noopener noreferrer\">Bigelow Aerospace<\/a> aus Nevada bekannt. Das Unternehmen wurde 1999 von <a href=\"https:\/\/de.wikipedia.org\/wiki\/Robert_Bigelow\" target=\"_blank\" rel=\"noopener noreferrer\">Robert Bigelow<\/a> gegr\u00fcndet und arbeitet an aufblasbaren Raummodulen mit einer entfaltbarer Au\u00dfenhaut aus Vectran. Der Vorteil: Die Module k\u00f6nnen auf der Erde zusammengefaltet auf der Spitze einer Rakete montiert und in den Weltraum geschossen werden. Dort werden Sie entfaltet und mit Luft gef\u00fcllt. Die Raummodule bieten dann sehr viel Platz. Bigelow Aerospace hat Touristen als Zielgruppe im Sinn.<\/p>\n<h2>Konzept der Sierra Nevada Corporation vorgestellt<\/h2>\n<p>Aber es schein noch weitere Firmen zu geben, die am Konzept der NASA f\u00fcr aufblasbare Weltraum-Habitate arbeiten. Dies entnehme ich dem nachfolgend gezeigten Tweet.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">The era of large, inflatable space habitats don't look so bad after all <a href=\"https:\/\/t.co\/o78SuETJrz\">https:\/\/t.co\/o78SuETJrz<\/a><\/p>\n<p>\u2014 Ars Technica (@arstechnica) <a href=\"https:\/\/twitter.com\/arstechnica\/status\/1166067163196743680?ref_src=twsrc%5Etfw\">August 26, 2019<\/a><\/p><\/blockquote>\n<p>Letzte Woche Mittwoch zeigte die <a href=\"https:\/\/de.wikipedia.org\/wiki\/Sierra_Nevada_Corporation\" target=\"_blank\" rel=\"noopener noreferrer\">Sierra Nevada Corporation<\/a> &#8211; ein Unternehmen, das Luft- und Raumfahrtausr\u00fcstung herstellt &#8211; zum ersten Mal seine Entwicklung. Das aufblasbare Weltraummodul ist mehr als 8 Meter lang und hat mit einem Durchmesser von 8 Metern ein Innenvolumen von 300 Kubikmetern. Das entspricht in etwa einem Drittel der Gr\u00f6\u00dfe der Internationalen Raumstation. Hier das Video mit der Vorstellung des Moduls.<\/p>\n<p>(Quelle: <a href=\"https:\/\/youtu.be\/FEmoqRp8_dw\">YouTube<\/a>)<\/p>\n<p>Die <a href=\"https:\/\/web.archive.org\/web\/20210507153010\/https:\/\/www.sncorp.com\/space-systems\" target=\"_blank\" rel=\"noopener noreferrer\">Sierra Nevada Corporation<\/a> entwickelte diesen Prototyp im Rahmen eines NASA-Programms (ein weiterer Artikel in Englisch findet sich <a href=\"https:\/\/www.space.com\/sierra-nevada-inflatable-habitat-moon-gateway.html\" target=\"_blank\" rel=\"noopener noreferrer\">hier<\/a>). Dies NASA finanzierte mehrere Unternehmen, um Moduls zu entwickeln, die f\u00fcr eine Raumstation im Orbit um den Mond genutzt werden k\u00f6nnten.<\/p>\n<h2>Wohnraum f\u00fcr die Mondumlaufbahn oder den Mars-Flug<\/h2>\n<p>Die Module sind potenziell auch als Wohnraum f\u00fcr einen Langzeittransit vom und zum Mars geplant. Als Teil des Programms haben oder werden NASA-Astronauten drei Tage lang in den von Sierra Nevada, Boeing, Lockheed Martin, Northrop Grumman und Bigelow Aerospace gebauten Prototypen leben und diese auswerten. Folgende Video zeigt das Konzept eines Moduls in der Mondumlaufbahn.<\/p>\n<p>(Quelle: <a href=\"https:\/\/youtu.be\/Xp_ZODcQcx8\">YouTube<\/a>)<\/p>\n<p>Das Verkaufsargument f\u00fcr das Weltraum-Habitat von Sierra Nevada ist dessen Gr\u00f6\u00dfe. Dazu wird das mehrschichtige Gewebematerial zum Start komprimiert. Damit passt es in eine Standard-Nutzlastverkleidung, die f\u00fcr Tr\u00e4gerraketen wie die Falcon Heavy Rakete von SpaceX, den Vulcan-Booster der United Launch Alliance oder das Space Launch System der NASA. Es ist zudem leicht genug, dass eine dieser Raketen zum Mond starten kann. Im Weltraum l\u00e4sst es sich dann entfalten und kann als Lebensraum f\u00fcr Bewohner dienen.<\/p>\n<p>\"Wir bieten eine riesige Menge an Volumen auf engstem Raum\", sagte der f\u00fcnfmalige NASA-Astronaut Steve Lindsey, Vizepr\u00e4sident der Space Exploration Systems des Unternehmens. Was dieses Modul derzeit nicht hat, ist ein genauer Zweck. Lindsey sagte, dass der aufblasbare Weltraum-Lebensraum, der technologisch einige \u00c4hnlichkeiten mit dem erweiterbaren Modul von Bigelow aufweist, f\u00fcr eine beliebige Anzahl von Missionen bemessen sein k\u00f6nnte, von einer Raumstation mit niedriger Erdumlaufbahn bis hin zu einem Lebensraum auf der Oberfl\u00e4che des Mondes oder Mars. Ein Modul von Bigelow Aerospace ist bereits zu Versuchszwecken an der Internationalen Raumstation angebracht.<\/p>\n<p>Die NASA hatte urspr\u00fcnglich die Entwicklung dieser Prototypen f\u00fcr ihr <a href=\"https:\/\/arstechnica.com\/science\/2016\/10\/six-contractors-have-begun-work-on-nasas-gateway-to-deep-space\/\" target=\"_blank\" rel=\"noopener noreferrer\">NextSTEP-2-Programm<\/a> zur Entwicklung eines Lebensraummoduls f\u00fcr das Mond-Gateway, eine Raumstation in einer Umlaufbahn um den Mond, geplant. Dies sollte eine ziemlich gro\u00dfe Anlage werden, die Astronauten ein- bis zweimal im Jahr besuchen. Das Projekt ist aber den Pl\u00e4nen von US-President Donald Trump, bis 2024 auf dem Mond zu landen, zum Opfer gefallen.<\/p>\n<p>Mit der Vorstellung des geplanten Lebensraums am Mittwoch im Johnson Space Center will die Sierra Nevada der NASA und potenziellen Kunden das Potenzial f\u00fcr gro\u00dfe, massearme Lebensr\u00e4ume im Weltraum aufzeigen. Jetzt braucht das Unternehmen nur noch die NASA, um einige Anforderungen zu erf\u00fcllen. Wie lange bleiben Astronauten zum Beispiel auf der Mondoberfl\u00e4che? Wird die NASA irgendwann einen gr\u00f6\u00dferen Lebensraum f\u00fcr das Mond-Gateway wollen? Und ist es wirklich ernst damit, Menschen auf den Mars zu schicken?<\/p>\n<p><strong>\u00c4hnliche Artikel:<\/strong><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2018\/11\/20\/jubilum-20-jahre-internationale-raumstation-iss\/\">Jubil\u00e4um: 20 Jahre internationale Raumstation ISS<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2019\/04\/15\/mikroben-im-all-iss-voller-keime\/\">Mikroben im All, ISS voller Keime<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2018\/12\/18\/start-eines-soyus-raumschiffs-von-der-iss-gefilmt\/\">Start eines Soyus-Raumschiffs von der ISS gefilmt<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2018\/11\/25\/start-des-raumtransporters-gefilmt-von-der-iss\/\">Start des Raumtransporters, gefilmt von der ISS<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2019\/07\/21\/soyus-ms-13-im-anflug-an-die-iss\/\">Soyus MS-13 im Anflug an die ISS<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2019\/05\/31\/frhjahrsputz-auf-der-internationalen-raumstation-iss\/\">Fr\u00fchjahrsputz auf der internationalen Raumstation ISS<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2017\/12\/06\/pizza-backen-auf-der-iss\/\">Pizza backen auf der ISS<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2017\/11\/15\/langzeit-raumfahrtmissionen-wirken-sich-auf-das-gehirn-aus\/\">Langzeit-Raumfahrtmissionen wirken sich auf das Gehirn aus<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2018\/12\/21\/vor-50-jahren-apollo-8-mission-zur-mondumkreisung\/\">Vor 50 Jahren: Apollo 8 Mission zur Mondumkreisung<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2019\/05\/28\/vor-60-jahren-miss-able-und-miss-baker-zum-weltraumhopser\/\">Vor 60 Jahren: Miss Able und Miss Baker zum Weltraumhopser<\/a><br \/>\n<a href=\"https:\/\/web.archive.org\/web\/20240527012847\/https:\/\/borncity.eu\/senioren\/2019\/08\/26\/andockmanver-an-iss-gescheitert\/\">Andockman\u00f6ver an ISS gescheitert<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2019\/07\/30\/wie-lebt-es-sich-auf-der-internationalen-raumstation-iss\/\">Wie lebt es sich auf der Internationalen Raumstation (ISS)?<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In den USA hat eine Firma gerade ausblasbare Weltraum-Aufenthaltsmodule vorgestellt. Diese k\u00f6nnten sp\u00e4ter f\u00fcr den Flug zu Mond oder den Mars dienen, bieten sie den Raumfahrern doch mehr Platz als heutige Raumkapseln. Vor allem sind die Module leicht und lassen &hellip; <a href=\"https:\/\/borncity.eu\/senioren\/2019\/08\/29\/aufblasbare-weltraum-habitate-im-kommen\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[655],"tags":[222],"class_list":["post-10052","post","type-post","status-publish","format-standard","hentry","category-technik","tag-raumfahrt"],"_links":{"self":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/posts\/10052","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/comments?post=10052"}],"version-history":[{"count":2,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/posts\/10052\/revisions"}],"predecessor-version":[{"id":26727,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/posts\/10052\/revisions\/26727"}],"wp:attachment":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/media?parent=10052"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/categories?post=10052"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/tags?post=10052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}