{"id":10589,"date":"2019-10-30T17:41:19","date_gmt":"2019-10-30T16:41:19","guid":{"rendered":"https:\/\/borncity.com\/senioren\/?p=10589"},"modified":"2019-10-30T17:41:19","modified_gmt":"2019-10-30T16:41:19","slug":"zug-der-kraniche-der-winter-kommt","status":"publish","type":"post","link":"https:\/\/borncity.eu\/senioren\/2019\/10\/30\/zug-der-kraniche-der-winter-kommt\/","title":{"rendered":"Zug der Kraniche, der Winter kommt"},"content":{"rendered":"<p>Bereits Mitte Oktober 2018 hat mir meine Frau \u00fcber die ersten Kranich-Schw\u00e4rme auf dem Flug gegen S\u00fcden berichtet. In den letzten Tagen haben dann weitere Schw\u00e4rme den Weg in den S\u00fcden angetreten.<\/p>\n<p><!--more--><\/p>\n<p>Heute haben wir wieder Ostwind \u2013 und es zogen mehrere Kranich-Schw\u00e4rme \u00fcber den Taunus und unseren Ort in Richtung Rhein und weiter nach S\u00fcden. Dieses Foto entstand mit dem Smartphone, als ich von einem Spaziergang aus dem Wald trat und die Schreie der Wildg\u00e4nse vernahm. <\/p>\n<p><img decoding=\"async\" title=\"Kranichzug Herbst 2019\" alt=\"Kranichzug Herbst 2019\" src=\"https:\/\/i.imgur.com\/12pUwPI.jpg\"><br \/>(Kranichzug Herbst 2019)<\/p>\n<p>Das hei\u00dft, dass der Winter im Anmarsch ist \u2013 aktuell wird es auch k\u00e4lter. Jetzt gilt es die Monate November und Dezember zu \u00fcberstehen, um sich im Januar auf den nahenden Fr\u00fchling zu freuen. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bereits Mitte Oktober 2018 hat mir meine Frau \u00fcber die ersten Kranich-Schw\u00e4rme auf dem Flug gegen S\u00fcden berichtet. In den letzten Tagen haben dann weitere Schw\u00e4rme den Weg in den S\u00fcden angetreten.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[119],"class_list":["post-10589","post","type-post","status-publish","format-standard","hentry","category-natur","tag-natur"],"_links":{"self":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/posts\/10589","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/comments?post=10589"}],"version-history":[{"count":0,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/posts\/10589\/revisions"}],"wp:attachment":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/media?parent=10589"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/categories?post=10589"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/tags?post=10589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}