{"id":11015,"date":"2019-12-23T00:20:00","date_gmt":"2019-12-22T23:20:00","guid":{"rendered":"https:\/\/borncity.com\/senioren\/?p=11015"},"modified":"2023-08-02T00:31:16","modified_gmt":"2023-08-01T22:31:16","slug":"heilig-abend-das-liegt-unterm-weihnachtsbaum","status":"publish","type":"post","link":"https:\/\/borncity.eu\/senioren\/2019\/12\/23\/heilig-abend-das-liegt-unterm-weihnachtsbaum\/","title":{"rendered":"Heilig Abend: Das liegt unterm Weihnachtsbaum"},"content":{"rendered":"<p><img decoding=\"async\" style=\"float: left; margin: 0px 10px 0px 0px; display: inline\" alt=\"\" src=\"https:\/\/borncity.eu\/senioren\/wp-content\/uploads\/2024\/11\/DNxhm89.jpg\">281 Euro geben die&nbsp; Deutschen dieses Jahr pro Kopf f\u00fcr Weihnachtsgeschenke aus. H\u00e4ndler setzen im Weihnachtsgesch\u00e4ft 18,4 Milliarden Euro um. So viel ist dank einer Studie der Wirtschaftsberatung EY bekannt. Nicht bekannt ist, was Heiligabend unterm Weihnachtsbaum liegt. <\/p>\n<p><!--more--><\/p>\n<p>Die Betreiber von mydealz, der gr\u00f6\u00dften deutschen Shopping-Community, haben versucht, dieses Geheimnis zu l\u00fcften. Sie haben analysiert, f\u00fcr welche Produkte sich die Mitglieder der mydealz-Community seit dem 1. Oktober am meisten interessiert haben<b>.<\/b><\/p>\n<p><strong><\/strong>&nbsp;<\/p>\n<h2>Praktische Dinge beliebt<strong><img loading=\"lazy\" decoding=\"async\" title=\"Weihnachten\" alt=\"Weihnachten\" src=\"https:\/\/images.pexels.com\/photos\/3224164\/pexels-photo-3224164.jpeg?auto=compress&amp;cs=tinysrgb&amp;h=750&amp;w=1260\" width=\"640\" height=\"821\"><br \/><\/strong><\/h2>\n<p>(Quelle: Pexels <a href=\"https:\/\/www.pexels.com\/de-de\/@hert-niks-1495637\" target=\"_blank\" rel=\"noopener noreferrer\">Hert Nikx<\/a>, Freie Nutzung)<\/p>\n<p>Die meisten Konsumenten verschenken dieses Jahr nicht Spielzeug oder Unterhaltungselektronik, sondern praktischere Dinge.  <\/p>\n<ul>\n<li>Jeder sechste der 51,8 Millionen Kaufinteressenten (16,4 Prozent), die mydealz vom 1. Oktober bis zum 6. Dezember 2019 vermittelt hat, entschied sich f\u00fcr M\u00f6bel und Dekoartikel.\n<li>15,5 Prozent interessierten sich f\u00fcr Haushaltsger\u00e4te wie Staubsaugerroboter und Smart-Home-Ger\u00e4te.\n<li>Und immerhin noch rund jeder Achte (12,6 Prozent) verschenkt dieses Jahr zu Weihnachten Mode und Accessoires.\n<li>Spielzeug \u2013 in fr\u00fcheren Jahren der Bestseller im Weihnachtsgesch\u00e4ft \u2013 liegt dieses Jahr \u00fcberraschender Weise nur auf dem vierten Rang der beliebtesten Geschenke. Nur knapp jeder Zehnte (9,2 Prozent) hat bislang Spielzeug gekauft.\n<li>\u00c4hnlich beliebt sind Smartphones und Tablets, die dieses Jahr 8,7 Prozent der Konsumenten verschenken. Mobile Endger\u00e4te vervollst\u00e4ndigen damit die Top-5 der im Weihnachtsgesch\u00e4ft nachfragest\u00e4rksten Warengruppen.\n<li>Mit Parf\u00fcm und Kosmetika f\u00fchrt ein weiteres klassisches Weihnachtsgeschenk die zweite H\u00e4lfte der Top-10 des Geschenkerankings an. 8,2 Prozent der Verbraucher verschenken dieses Jahr Parf\u00fcms und Kosmetika wie Mascara oder Lipgloss.\n<li>Dass wir Deutschen gerne Elektronik verschenken, macht ein Blick auf Rang sieben und acht des Geschenkerankings klar. Hier liegen Kameras (6,2 Prozent) und Fernseher sowie HiFi-Ger\u00e4te (6,1 Prozent).\n<li>Lebensmittel folgen auf Rang neun: Jeder Zwanzigste (4,8 Prozent) m\u00f6chte dieses Jahr Delikatessen, Pralinen, Weine und Spirituosen zu Weihnachten verschenken.\n<li>Erotikartikel vervollst\u00e4ndigen die Top-10 der beliebtesten Weihnachtsgeschenke. 3,4 Prozent der Deutschen m\u00f6chten ihre Partnerin oder ihren Partner dieses Jahr an Heiligabend mit Dessous oder Sextoys \u00fcberraschen und dem Weihnachtsfest so eine besondere Note verleihen<\/li>\n<\/ul>\n<p>Die oben stehenden Aussagen sind das Ergebnis einer Analyse, die die Betreiber der Shopping-Community mydealz f\u00fcr die Zeit vom 1. Oktober bis zum 6. Dezember 2019 durchgef\u00fchrt haben. Bei mydealz teilen und bewerten registrierte Mitglieder aktuelle Angebote von Online-Shops, klassischen H\u00e4ndlern und anderen Anbietern verschiedenster Warengruppen. Links f\u00fchren zum jeweiligen Angebot. <\/p>\n<p>Um zu ermitteln, in welcher Warengruppe die Nachfrage am st\u00e4rksten ist, haben die mydealz-Betreiber analysiert, wie oft Verbraucher (\u201eKaufinteressenten\") Links zu Angeboten der jeweiligen Warengruppe mit der Absicht gefolgt sind, die angebotenen Produkte zu kaufen.<\/p>\n<p>Quelle: <a href=\"https:\/\/web.archive.org\/web\/20220930190146\/https:\/\/www.ey.com\/de_de\/news\/2019\/11\/deutsche-bleiben-zu-weihnachten-spendabel\" target=\"_blank\" rel=\"noopener noreferrer\">Deutsche bleiben zu Weihnachten spendabel: Geschenkbudgets fast auf dem Rekordniveau des Vorjahres<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>281 Euro geben die&nbsp; Deutschen dieses Jahr pro Kopf f\u00fcr Weihnachtsgeschenke aus. H\u00e4ndler setzen im Weihnachtsgesch\u00e4ft 18,4 Milliarden Euro um. So viel ist dank einer Studie der Wirtschaftsberatung EY bekannt. Nicht bekannt ist, was Heiligabend unterm Weihnachtsbaum liegt.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[168],"class_list":["post-11015","post","type-post","status-publish","format-standard","hentry","category-allgemein","tag-allgemein"],"_links":{"self":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/posts\/11015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/comments?post=11015"}],"version-history":[{"count":1,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/posts\/11015\/revisions"}],"predecessor-version":[{"id":23055,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/posts\/11015\/revisions\/23055"}],"wp:attachment":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/media?parent=11015"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/categories?post=11015"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/tags?post=11015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}