{"id":1314,"date":"2016-07-02T14:31:42","date_gmt":"2016-07-02T12:31:42","guid":{"rendered":"http:\/\/borncity.com\/senioren\/?p=1314"},"modified":"2020-04-23T18:58:40","modified_gmt":"2020-04-23T16:58:40","slug":"dahner-mittelalterliche-erlebnistage-2-3-juli-2016","status":"publish","type":"post","link":"https:\/\/borncity.eu\/senioren\/2016\/07\/02\/dahner-mittelalterliche-erlebnistage-2-3-juli-2016\/","title":{"rendered":"Dahner mittelalterliche Erlebnistage (2.\/3. Juli 2016)"},"content":{"rendered":"<p>Noch ein kleiner Tipp zum Wochenende f\u00fcr alle Blog-Leser aus der Pfalz oder der Umgebung der Verbandsgemeinde Dahn. Am 2.\/3. Juli 2016 finden in Dahn die nittelalterlichen Erlebnistage statt. Samstag zwischen 11 und 18 Uhr und Sonntag zwischen 11 und 17 Uhr werden l\u00e4ngst vergangene Zeiten zum Leben erweckt. Informationen lassen sich hier nachlesen (gel\u00f6scht). Und als Tipp f\u00fcr Kurzurlauber oder Wanderfreunde: Die S\u00fcd-Pfalz samt dem Felsenland Dahn ist immer eine Reise wert (siehe <a href=\"http:\/\/borncity.com\/reisen\/2014\/10\/02\/felsenland-dahn-wasgau-pflzerwald\/\" target=\"_blank\" rel=\"noopener noreferrer\">Felsenland Dahn (Wasgau, Pf\u00e4lzerwald<\/a>) in meinem Reise-Blog).&nbsp; <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Noch ein kleiner Tipp zum Wochenende f\u00fcr alle Blog-Leser aus der Pfalz oder der Umgebung der Verbandsgemeinde Dahn. Am 2.\/3. Juli 2016 finden in Dahn die nittelalterlichen Erlebnistage statt. Samstag zwischen 11 und 18 Uhr und Sonntag zwischen 11 und &hellip; <a href=\"https:\/\/borncity.eu\/senioren\/2016\/07\/02\/dahner-mittelalterliche-erlebnistage-2-3-juli-2016\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[168],"class_list":["post-1314","post","type-post","status-publish","format-standard","hentry","category-allgemein","tag-allgemein"],"_links":{"self":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/posts\/1314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/comments?post=1314"}],"version-history":[{"count":0,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/posts\/1314\/revisions"}],"wp:attachment":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/media?parent=1314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/categories?post=1314"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/tags?post=1314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}