{"id":16263,"date":"2021-03-22T08:31:14","date_gmt":"2021-03-22T07:31:14","guid":{"rendered":"https:\/\/borncity.com\/senioren\/?p=16263"},"modified":"2021-03-22T09:33:04","modified_gmt":"2021-03-22T08:33:04","slug":"weniger-verkehrstote-2020-aber-radfahrer-vorne","status":"publish","type":"post","link":"https:\/\/borncity.eu\/senioren\/2021\/03\/22\/weniger-verkehrstote-2020-aber-radfahrer-vorne\/","title":{"rendered":"Weniger Verkehrstote 2020, aber Radfahrer vorne und Pedelec-Fahrer-Unf&auml;lle steigen"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" style=\"float: left; margin: 0px 10px 0px 0px; display: inline\" src=\"https:\/\/www.borncity.com\/blog\/wp-content\/uploads\/2015\/01\/Schutz.jpg\" width=\"40\" height=\"47\">Das Statistische Bundesamt in Wiesbaden hat k\u00fcrzlich Zahlen zu Verkehrsunf\u00e4llen mit Personenschaden im Jahr 2020 vorgelegt. Es f\u00e4llt auf, dass Radfahrer und vor allem die bei \u00c4lteren beliebten E-Bike-Piloten nach wie vor in hohem Ma\u00dfe in t\u00f6dliche Unf\u00e4lle verwickelt sind.<\/p>\n<p><!--more--><\/p>\n<p>Wegen Corona ging der Verkehr im Jahr 2020 zur\u00fcck, <a href=\"https:\/\/www.destatis.de\/DE\/Presse\/Pressemitteilungen\/2021\/02\/PD21_084_46.html\" target=\"_blank\" rel=\"noopener\">teilte<\/a> das Statistische Bundesamt in Wiesbaden mit. Im Jahr 2020 sind in Deutschland 2 724 Menschen bei Unf\u00e4llen im Stra\u00dfenverkehr ums Leben gekommen. Wie das Statistische Bundesamt (Destatis) nach vorl\u00e4ufigen Ergebnissen weiter mitteilt, waren das 322 Todesopfer oder 10,6 % weniger als im Jahr 2019 (3 046 Todesopfer). Damit erreichte die Zahl der Verkehrstoten den niedrigsten Stand seit Beginn der Statistik vor mehr als 60 Jahren. Auch die Zahl der Verletzten ging 2020 gegen\u00fcber dem Vorjahr zur\u00fcck, und zwar um 14,7 % auf rund 328 000 Personen.<\/p>\n<p><a href=\"https:\/\/twitter.com\/tuvcom_presse\/status\/1347145762682114054\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" title=\"Verkehrsunf&auml;lle mit Personenschaden\" alt=\"Verkehrsunf&auml;lle mit Personenschaden\" src=\"https:\/\/i.imgur.com\/YIshuSo.png\"><\/a><\/p>\n<h2>Pedelecs mit steigenden t\u00f6dlichen Unf\u00e4llen<\/h2>\n<p>Das ist die gute Nachricht. Auch bei Radfahrern, die auf Fahrr\u00e4dern (ohne Hilfsmotor) unterwegs waren, sank die Zahl der Get\u00f6teten um 12,9 % (40 Tote weniger) gegen\u00fcber 2019. Leider sind dies immer noch 271 Menschen, jeder f\u00fcr sich ein tragisches Einzelschicksal, gestorben. Und was aufmerken l\u00e4sst: Die die Zahl der get\u00f6teten Pedelecfahrerinnen und -fahrer nahm von Januar bis November 2020 um 22 (19,1 %) auf 137 Personen zu. Die Ursache ist noch unklar &#8211; aber vom Bauchgef\u00fchl her ist es die \u00dcbersch\u00e4tzung der Pedelec-Piloten, die zu solchen t\u00f6dlichen Unf\u00e4llen f\u00fchrt. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Statistische Bundesamt in Wiesbaden hat k\u00fcrzlich Zahlen zu Verkehrsunf\u00e4llen mit Personenschaden im Jahr 2020 vorgelegt. Es f\u00e4llt auf, dass Radfahrer und vor allem die bei \u00c4lteren beliebten E-Bike-Piloten nach wie vor in hohem Ma\u00dfe in t\u00f6dliche Unf\u00e4lle verwickelt sind.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,655],"tags":[195,724],"class_list":["post-16263","post","type-post","status-publish","format-standard","hentry","category-sicherheit","category-technik","tag-unfall","tag-verkehr"],"_links":{"self":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/posts\/16263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/comments?post=16263"}],"version-history":[{"count":0,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/posts\/16263\/revisions"}],"wp:attachment":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/media?parent=16263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/categories?post=16263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/tags?post=16263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}