{"id":1718,"date":"2016-10-12T08:11:00","date_gmt":"2016-10-12T06:11:00","guid":{"rendered":"http:\/\/borncity.com\/senioren\/?p=1718"},"modified":"2023-11-21T06:49:59","modified_gmt":"2023-11-21T05:49:59","slug":"steuererklrung-fr-rentner-ausfllhilfe-anfordern","status":"publish","type":"post","link":"https:\/\/borncity.eu\/senioren\/2016\/10\/12\/steuererklrung-fr-rentner-ausfllhilfe-anfordern\/","title":{"rendered":"Steuererkl&auml;rung f&uuml;r Rentner: Ausf&uuml;llhilfe anfordern"},"content":{"rendered":"<p><img decoding=\"async\" style=\"float: left; margin: 0px 10px 0px 0px; display: inline;\" src=\"https:\/\/borncity.eu\/senioren\/wp-content\/uploads\/2024\/11\/DNxhm89.jpg\" alt=\"\" align=\"left\" \/>Eink\u00fcnfte aus der gesetzlichen Rentenversicherung sind, wie andere Rentenzahlungen, steuerpflichtig. Immer mehr deutsche Rentner m\u00fcssen daher eine Steuererkl\u00e4rung ausf\u00fcllen. Aber wie findet man sich im Dschungel der Steuerformulare zurecht?<\/p>\n<p><!--more--><\/p>\n<p>Wer mit seiner gesetzlichen Rente einen gewissen Betrag \u00fcberschreitet und sonstige Einnahmen hat, ist zur Abgabe einer Steuererkl\u00e4rung verpflichtet. Die Rentenerh\u00f6hungen der letzten Zeit f\u00fchren dazu, dass immer mehr Rentner eine Steuererkl\u00e4rung abgeben m\u00fcssen. Das kostet M\u00fche und ist mitunter kompliziert. Man kann sich diese M\u00fche wesentlich erleichtern (danke an Marc f\u00fcr diesen Tipp).<\/p>\n<h3>Tipp: Ausf\u00fcllhilfe beantragen<\/h3>\n<p>Die Deutsche Rentenversicherung stellt Rentnern auf Wunsch kostenlos eine Bescheinigung aus (siehe <a href=\"https:\/\/web.archive.org\/web\/20160608011631\/http:\/\/www.deutsche-rentenversicherung.de:80\/Allgemein\/de\/Inhalt\/5_Services\/rententipp\/drv_unterstuetzt_bei_steuererklaerung_2014.html\" target=\"_blank\" rel=\"noopener\">diese Webseite<\/a>), die beim<b>\u00a0<\/b>Ausf\u00fcllen der Steuervordrucke <em>Anlage R<\/em> und <em>Anlage Vorsorgeaufwand<\/em> hilft. Diese Bescheinigung enth\u00e4lt alle steuerrechtlich relevanten Betr\u00e4ge mit Hinweisen, in welchen Zeilen der beiden Erkl\u00e4rungsvordrucke diese Werte einzutragen sind.<\/p>\n<p>Die Bescheinigung k\u00f6nnen Versicherte per Brief, Fax oder E-Mail bei Ihrem Rentenversicherungstr\u00e4ger anfordern. M\u00f6glich ist auch ein Anruf beim kostenlosen Servicetelefon der Deutschen Rentenversicherung unter der Telefonnummer <em>0800 1000 4800<\/em><b>.<\/b> <a href=\"https:\/\/web.archive.org\/web\/20170224095742\/http:\/\/www.vdk.de:80\/nrw\/pages\/sozialpolitik\/rente\/27810\/steuererklaerung_bescheinigung_erleichtert_rentnern_das_ausfuellen\" target=\"_blank\" rel=\"noopener\">Beim VDK<\/a> wird zudem das B\u00fcrgertelefon 0800-1000 48013 genannt.<\/p>\n<p>Bei dieser Anforderung muss die pers\u00f6nliche Rentenversicherungsnummer angegeben werden! Wer eine Hinterbliebenenrente bezieht, muss auch die zu dieser Rente geh\u00f6rende Versicherungsnummer nennen.<\/p>\n<p>Wer die Bescheinigung einmal beantragt hat, erh\u00e4lt sie fortan j\u00e4hrlich <em>automatisch<\/em> von der Deutschen Rentenversicherung zugesandt. Zur Besteuerung von \"Auslandsrenten\" m\u00f6chte ich auf <a href=\"https:\/\/web.archive.org\/web\/20180120065101\/http:\/\/www.finanztip.de:80\/rentner-im-ausland\/\" target=\"_blank\" rel=\"noopener\">diesen Finanztipp<\/a> und diese <a href=\"https:\/\/www.steuertipps.de\/altersvorsorge-rente\/rentner-pensionaere\/als-rentner-im-ausland-leben-wer-muss-eine-steuererklaerung-abgeben\" target=\"_blank\" rel=\"noopener\">Steuertipps-Seite<\/a> verweisen. Und <a href=\"https:\/\/web.archive.org\/web\/20190407042131\/https:\/\/www.deutsche-rentenversicherung.de\/Allgemein\/de\/Navigation\/5_Services\/04_formulare_und_antraege\/01_versicherte\/ausland_node.html\" target=\"_blank\" rel=\"noopener\">diese Seite<\/a> der Deutsche Rentenversicherung befasst sich mit Rententhemen im Ausland.<\/p>\n<p><strong>Artikelreihe:<\/strong><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/?p=1713\">Tipp: Die Rentenberatung der Deutsche Rentenversicherung<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/?p=1718\">Steuererkl\u00e4rung f\u00fcr Rentner: Ausf\u00fcllhilfe anfordern<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/?p=1724\">Rentenantr\u00e4ge bei der Deutsche Rentenversicherung anfordern<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/?p=1728\">Tipp: Erg\u00e4nzende Informationen f\u00fcr Rentner bei der DRV<\/a><\/p>\n<p><strong>\u00c4hnliche Artikel:<\/strong><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2016\/09\/12\/arbeiten-im-ruhestand-immer-mehr-tun-es\/\">Arbeiten im Ruhestand\u2013immer mehr tun es<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2015\/07\/05\/was-die-euro-krise-fr-deutsche-sparer-bedeutet\/\">Was die Euro-Krise f\u00fcr deutsche Sparer bedeutet<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eink\u00fcnfte aus der gesetzlichen Rentenversicherung sind, wie andere Rentenzahlungen, steuerpflichtig. Immer mehr deutsche Rentner m\u00fcssen daher eine Steuererkl\u00e4rung ausf\u00fcllen. Aber wie findet man sich im Dschungel der Steuerformulare zurecht?<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[326,324,327],"class_list":["post-1718","post","type-post","status-publish","format-standard","hentry","category-allgemein","tag-deutsche-rentenversicherung","tag-rente","tag-steuern"],"_links":{"self":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/posts\/1718","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/comments?post=1718"}],"version-history":[{"count":1,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/posts\/1718\/revisions"}],"predecessor-version":[{"id":23785,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/posts\/1718\/revisions\/23785"}],"wp:attachment":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/media?parent=1718"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/categories?post=1718"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/tags?post=1718"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}