{"id":18044,"date":"2021-11-17T00:18:00","date_gmt":"2021-11-16T23:18:00","guid":{"rendered":"https:\/\/borncity.com\/senioren\/?p=18044"},"modified":"2025-06-12T16:01:27","modified_gmt":"2025-06-12T14:01:27","slug":"mein-gipfelsturm-auf-den-wilseder-berg","status":"publish","type":"post","link":"https:\/\/borncity.eu\/senioren\/2021\/11\/17\/mein-gipfelsturm-auf-den-wilseder-berg\/","title":{"rendered":"Mein Gipfelsturm auf den Wilseder Berg &#8230;"},"content":{"rendered":"<p><img decoding=\"async\" style=\"float: left; margin: 0px 10px 0px 0px; display: inline;\" title=\"Wilseder Berg; Quelle: Willow CC BY 2.5 Wikimedia\" src=\"https:\/\/i.imgur.com\/r7qz98d.png\" alt=\"Wilseder Berg; Quelle: Willow CC BY 2.5 Wikimedia\" align=\"left\" \/>Heute mal wieder eine sehr spezielle Geschichte, die mir in diesem Leben vor vielen, vielen Jahren, genau gesagt, am 12. April 1981, pers\u00f6nlich passiert ist. Ich hatte mich, auf Einladung von guten Freunden, zum Gipfelsturm auf den Wilseder Berg eingefunden. Ist aber eine etwas melancholische Geschichte, denn damals war Jugend, und wir wollten die Sterne vom Himmel holen. Die Freunde wollten mir dabei etwas Gutes tun, damit ich endlich wieder Berge sehe. Ist aber irgendwie schief gegangen. Und diese Vergangenheit hat mich k\u00fcrzlich eingeholt.<\/p>\n<p><!--more--><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/vg08.met.vgwort.de\/na\/b65b3e449f24486dbf1571c2a3db1b1a\" alt=\"\" width=\"1\" height=\"1\" \/>Die Erinnerung geweckt hat ein pers\u00f6nlicher Facebook-Post einer meiner ehemaligen Markt+Technik-Lektoren aus M\u00fcnchen. J\u00f6rg war heuer auf Urlaub im Norden und postete ein Foto mit dem Text \"<em>H\u00f6chster Punkt der L\u00fcneburger Heide. Leider kein Gipfelbuch vorhanden &#8230;<\/em>\".<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/i.imgur.com\/HZ1wNSE.png\" \/><\/p>\n<p>Mit dem h\u00f6chsten Berg in der L\u00fcneburger Heide ist der <a href=\"https:\/\/de.wikipedia.org\/wiki\/Wilseder_Berg\" target=\"_blank\" rel=\"noopener\">Wilseder Berg<\/a> gemeint, der sich auf wuchtige 169,2 Meter Normalh\u00f6he erhebt. Entstanden ist die Erhebung w\u00e4hrend der vorletzten Eiszeit, der Saaleeiszeit; es handelt sich dabei um einen Teil einer Endmor\u00e4ne. Der Berg hat ein ausgedehntes Hochplateau und einen flachen Gipfel. An den R\u00e4ndern ist er vielgestaltig ausgepr\u00e4gt mit Mulden, T\u00e4lern und kleinen Schluchten. Aber das wusste ich 1981 alles nicht, wenn mir auch der Name des \"Bergs\" ein Begriff war.<\/p>\n<p>Und zum Thema Gipfelbuch noch ein kurzer Hinweis: Wer in M\u00fcnchen lebt, kraxelt auch schon mal in den Alpen herum, und auf diesen Bergen gibt es dann ein Gipfelbuch &#8211; meist beim Gipfelkreuz, verstaut in einer Blechkiste &#8211; in das sich der Wanderer\/Kletterer eintragen kann. Klar, dass J\u00f6rg das Gipfelbuch vermisst hat &#8230;<\/p>\n<h2>Depressiver Norden<\/h2>\n<p>Als ich Anfang Oktober 2021 den obigen Post auf Facebook mit dem Gipfelstein sah, war sofort mein pers\u00f6nliches Erlebnis mit dem Wilseder Berg vom 12. April 1981 wieder pr\u00e4sent. Ist eine pers\u00f6nliche, aber auch etwas traurige Geschichte. Zwischen 1979 und 1981 habe ich als frisch gebackener Ingenieur in der Luft- und Raumfahrtindustrie in Bremen gearbeitet. Die flache Wesermarsch h\u00e4tte mich fast in Depressionen getrieben, weil mir die \"Berge\" (oder zumindest die H\u00fcgel, die ich aus der Eifel kannte) fehlten. Und mit der Art der Norddeutschen hatte ich in Bremen auch so gewisse Probleme, Rheinl\u00e4nder sind anders &#8211; auch wenn Menschen aus der Eifel etwas maulfauler sind.<\/p>\n<p>Jedenfalls vermisste ich die bewaldeten H\u00fcgel der Eifel massiv. Und pl\u00f6tzlich war irgendwie alles doof. Wenn wir Weihnachten oder Ostern von Bremen in die Eifel fuhren, und ich dann die Vulkanh\u00fcgel der Eifel bei Mayen sah, ging mir das Herz auf. Und dann die bewaldeten H\u00fcgel der Eifel, wo ich von den Feldern rund um unseren Bauernhof bis zur 20 km entfernten Mosel sehen konnte. Da ging es mir immer schlagartig besser. Meiner Frau machte der flache Norden dagegen nichts aus &#8230;<\/p>\n<h2>Und kommt der Berg nicht zum Propheten &#8230;<\/h2>\n<p>Ich hatte aber einen Arbeitskollegen, der als junger Ingenieur drei Monate vor mir beim Arbeitgeber seine erste Stelle angetreten hatte. Meine Frau und ich waren sehr schnell mit dem Kollegen und dessen Ehefrau, die im gleichen Alter waren, sehr, sehr gut befreundet. Wir haben viel zusammen unternommen. Beide stammten aus Norddeutschland und hatten mit der flachen Wesermarsch keine Probleme, merkten aber, dass es mir mental nicht so wirklich gut ging.<\/p>\n<p>An einem Wochenende luden sie uns ein, einen Berg in der Nachbarschaft Bremens zu besuchen, um mich in bessere Stimmung zu bringen. Das Angebot nahm ich mit meiner Frau gerne an, endlich w\u00fcrde ich wieder Berge, oder wenigstens einen Berg sehen. Den Namen der Erhebung habe ich vergessen &#8211; aber mir fiel die Kinnlade herunter, als ich gefragt wurde: \"Na, geht es dir jetzt besser, da ist dein Berg?\" und ich vor einem H\u00fcgelchen von vielleicht 10 bis 20 Meter H\u00f6he mit einigen B\u00e4umen drauf stand. F\u00fcr unsere Freunde, die im Norden geboren worden war, war das ein richtiger Berg &#8230;<\/p>\n<p>Was mir noch ein Erinnerung geblieben ist (ich meine jedenfalls, es war auf diesem Ausflug, m\u00f6glicherweise aber auch erst bei der Stippvisite zum Wilseder Berg): Nach dieser Entt\u00e4uschung, die auch unseren Freuden nicht verborgen blieb, kehrten wir noch in einem Caf\u00e9 ein, wo ich erstmals in meinem Leben ein St\u00fcck Buchweizentorte a\u00df. Buchweizen-Backwaren war seinerzeit kaum bekannt, aber das Ding schlechthin. War auch nicht so der Br\u00fcller &#8211; eigentlich ein total entt\u00e4uschendes Wochenende, hatte ich mich doch \"soo auf meinen Berg\" gefreut. Eigentlich h\u00e4tte ich den Beiden die F\u00fc\u00dfe vor Dankbarkeit k\u00fcssen m\u00fcssen, denn die haben quasi Handst\u00e4nde gemacht, um mich mental aufzubauen. Aber die Entt\u00e4uschung muss mir ins Gesicht geschrieben gewesen sein.<\/p>\n<h2>Exkursion zum Wilseder Berg<\/h2>\n<p>Nach dem ersten Reinfall wollten mir die Freunde dann doch eine Freude machen und etwas drauf satteln. Einige Wochen nach der obigen Episode kam der Vorschlag unserer Freunde\u00a0 \"lasse uns kommenden Sonntag zum Wilseder Berg fahren\". Der besagte Sonntag war der 12. April 1981, das Wetter war gut und es gab bei der Anfahrt auch keinen Stau.<\/p>\n<p>Wieso ich nach 40 Jahren noch wei\u00df, was ich am Sonntag den 12. April 1981 getrieben habe? Na klar, der Gipfelsturm zum Wilseder Berg hat sich unausl\u00f6schlich in meine jugendlichen Erinnerungen gebrannt. Wenn das Stichwort Wilseder Berg f\u00e4llt, steht sofort 12. April 1981 vor meinem geistigen Auge &#8211; selbst Nachts um halb Eins. Ok, ok, ich habe jetzt schamlos geflunkert, was das Datum betrifft. Im Hinterkopf war bei mir nur, dass es entweder 1980 oder 1981 so im Fr\u00fchjahr\/Sommer gewesen sein musste, als wir zu diesem Berg fuhren.<\/p>\n<p>Aber ich kann das Datum leicht recherchieren. Wenn wir heute zusammen telefonieren, ist bei den Freunden noch in Erinnerung, dass ich mit einem Batterie-betriebenen kleinen Transistorradio am Ohr unterwegs war. Sprich: Ich bin durch die Heide gelatscht, und habe die Live-Berichterstattung vom ersten <a href=\"https:\/\/de.wikipedia.org\/wiki\/STS-1\" target=\"_blank\" rel=\"noopener\">Start des US-Spaceshuttle Columbia<\/a> mit verfolgt. Und dieser Start erfolgte am Sonntag, den 12. April 1981. Dieses Ereignis des Spaceshuttle-Starts war f\u00fcr mich wichtig, arbeitete ich doch als junger Ingenieur in der Luft- und Raumfahrt. Studienkollegen von mir arbeiteten bei der Erno in Bremen am <a href=\"https:\/\/de.wikipedia.org\/wiki\/Spacelab\" target=\"_blank\" rel=\"noopener\">Spacelab<\/a> mit, welches am 28.11.1983 erstmals mit einem Spaceshuttle ins All flog.<\/p>\n<h2>Wo ist denn der Berg &#8230;<\/h2>\n<p>Bei mir gibt es dann noch die Erinnerung: Irgendwann habe ich das Radio abgeschaltet, weil das Spaceshuttle erfolgreich gestartet war. Nach l\u00e4ngerem Latschen in der Heide, bei dem wir den Schildern \"zum Wilseder Berg\" folgten,\u00a0 entfuhr es mir \"verdammt, wann sehen wir endlich den versprochenen Berg\". Als ich dann einen Wanderer sah, der vor einem Stein stand, fragte ich diesen \"k\u00f6nnen Sie mir sagen, wo wir den Wilseder Berg finden\". Der Mann schaute mich ganz entgeistert an und meinte, sie stehen doch drauf.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/i.imgur.com\/j7OnGbz.png\" \/><br \/>\nWilseder Berg, Gipfelstein mit Metallplatte mit Entfernungsangaben: die sogenannte Gau\u00df-S\u00e4ule, Quelle: MrsMyer <a href=\"http:\/\/creativecommons.org\/licenses\/by-sa\/3.0\/\" target=\"_blank\" rel=\"noopener\">CC BY-SA 3.0<\/a>, <a href=\"https:\/\/de.wikipedia.org\/wiki\/Wilseder_Berg#\/media\/Datei:WilsederBergGipfelstein.jpg\" target=\"_blank\" rel=\"noopener\">Wikimedia<\/a><\/p>\n<p>Gab damals noch keine Digitalkameras, also auch keine Fotos. Das obige Foto des Gipfelsteins sowie das eingangs gezeigte Foto des H\u00fcgelchens entstammen der <a href=\"https:\/\/de.wikipedia.org\/wiki\/Wilseder_Berg\" target=\"_blank\" rel=\"noopener\">Wikipedia-Seite<\/a>. Heute wird mir bewusst, wie bem\u00fcht unsere Freunde waren, um mir den Aufenthalt im Norden und in der flachen Wesermarsch ertr\u00e4glicher zu gestalten. Und die Freundschaft hat bis heute gehalten, nur hat die Entt\u00e4uschung \u00fcber den \"Berg im Norden\" bei mir einen Fluchtreflex ausgel\u00f6st.<\/p>\n<h2>Ich bin dann mal weg &#8230;<\/h2>\n<p>Zur Entt\u00e4uschung unserer Freunde habe ich den Abflug in Bremen gemacht und bin am 1. Juli 1981 &#8211; also vor fast genau 40 Jahren &#8211; in den Taunus (vor den Toren Frankfurts) gezogen. Da hatte es f\u00fcr mich Berge (keine Alpen, aber gen\u00fcgend H\u00fcgel, die mich an Eifel oder Schwarzwald erinnern). Ich bin dann im <a href=\"https:\/\/de.wikipedia.org\/wiki\/Taunus\" target=\"_blank\" rel=\"noopener\">Taunus<\/a> heimisch geworden und genie\u00dfe t\u00e4glich, wie genial die W\u00e4lder und die Ausblicke auf die H\u00fcgel dieses kleinen Gebirgsausl\u00e4ufers sind. Die depressive Stimmung, die mich im Norden befiel, war nach dem Umzug in den Taunus wie weggeblasen. Nachfolgendes Foto zeigt den Blick von meinem Hausberg, dem <a href=\"https:\/\/de.wikipedia.org\/wiki\/Staufen_(Taunus)\" target=\"_blank\" rel=\"noopener\">Staufen<\/a>, auf die Landschaft des Taunus mit dem <a href=\"https:\/\/de.wikipedia.org\/wiki\/Gro%C3%9Fer_Feldberg\" target=\"_blank\" rel=\"noopener\">Gro\u00dfen Feldberg<\/a>.<\/p>\n<p><img decoding=\"async\" title=\"Blick vom Staufen auf den Taunus\" src=\"https:\/\/i.imgur.com\/PRSsbsB.png\" alt=\"Blick vom Staufen auf den Taunus\" \/><br \/>\nBlick vom Staufen auf den Taunus<\/p>\n<p>Beruflich begann f\u00fcr mich mit dem Wechsel eine spannende Zeit (12 Jahre) als Ingenieur in der Gro\u00dfchemie, die mich bis nach <a href=\"https:\/\/borncity.com\/japan\/\" target=\"_blank\" rel=\"noopener\">Japan<\/a> f\u00fchrte. Dort habe ich dann mit der Besteigung des <a href=\"https:\/\/borncity.com\/japan\/2016\/02\/21\/der-ausflug-zum-fuji-teil-1\/\" target=\"_blank\" rel=\"noopener\">Fujijama (\u5bcc\u58eb\u5c71)<\/a> meinen pers\u00f6nlichen Gipfelsturm erlebt, und kann eine Besteigung eines echten Dreitausenders ins Buch des Lebens eintragen (der Fujiyama ist zwar ein Vulkan, aber mit 3776,24 Metern der h\u00f6chste Berg Japans). Aber das ist eine andere Geschichte, die ich in meinem Japan-Blog verewigt habe.<\/p>\n<p>In der Zeit von Juli 1981 bis September 1993 habe ich mir die IT-Grundlagen erarbeitet, um mir sp\u00e4ter die Meriten als IT-Autor und heute als Blogger zu verdienen. Waren gro\u00dfartige Berufsjahre, die mich vor 40 Jahren fast in den Abgrund gef\u00fchrt h\u00e4tten, weil es im Norden keine Berge gab (ich h\u00e4tte nach Norwegen gemusst).<\/p>\n<p>Aber heute ist alles gut &#8211; ich habe meine Berge vor Augen, kann t\u00e4glich durch die Taunusw\u00e4lder rennen und bin beruflich im Schlaraffenland. Denn 1993 habe ich mein Hobby zum Beruf gemacht und musste seit dieser Zeit nie wieder arbeiten. Denn seit 1988 schreibe ich Computerb\u00fccher oder Zeitschriftenartikel \u00fcber diese Thematik und lebe seit 1993 als freiberuflich t\u00e4tiger Autor davon.<\/p>\n<p>Seit 2007 bin ich als Blogger unterwegs, der sich seit 2016 \u00fcber diese Schiene finanziert. Inzwischen bin ich zwar Rentner, aber weiterhin als Blogger in einer Art Unruhestand, der die Schreibe noch nicht ganz an den Nagel h\u00e4ngen will. War eine lange Reise, wenn ich so zur\u00fcckblicke &#8211; und ich h\u00e4tte mir nie vorstellen k\u00f6nnen, dass mir mal Berge fehlen k\u00f6nnten.<\/p>\n<p><strong>\u00c4hnliche Artikel:<br \/>\n<\/strong><a href=\"https:\/\/borncity.eu\/senioren\/2021\/05\/17\/der-jung-soll-was-anstndiges-lernen\/\">Der Jung soll was anst\u00e4ndiges lernen<\/a><strong><br \/>\n<\/strong><a href=\"https:\/\/borncity.eu\/senioren\/?p=16713\">Meine \u201eSchrauberjahre\"-Teil 1: Der F\u00fchrerschein \u2026<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/?p=16723\">Meine \u201eSchrauberjahre\"-Teil 2: Das neue Moped \u2026<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/?p=16732\">Meine \u201eSchrauberjahre\"-Teil 3: Ein Auto wird gebraucht \u2026<\/a><\/p>\n<p><a href=\"https:\/\/borncity.eu\/senioren\/2021\/04\/22\/ich-pseudo-rentner\/\">Ich Pseudo-Rentner \u2026<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2021\/05\/07\/abenteuer-covid-19-impfung-wenn-borns-geimpft-werden\/\">Abenteuer COVID-19-Impfung: Wenn Borns geimpft werden<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2020\/09\/21\/heckenschnitt-ich-habe-den-reinhard-mey-gemacht\/\">Heckenschnitt: Ich habe den Reinhard Mey gemacht \u2026<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2020\/08\/26\/der-ritter-der-heckenschere-der-lavendel-schnitt\/\">Der Ritter der Heckenschere: Der Lavendel-Schnitt<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2019\/12\/19\/schuhkauf\/\">Der Schuhkauf \u2026<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2017\/07\/26\/gesunde-bewegung-der-kauf-der-barfuschuhe\/\">Gesunde Bewegung: Der Kauf der Barfu\u00dfschuhe<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2020\/07\/28\/ich-hab-die-marie-kondo-gemacht\/\">Ich hab die Marie Kond\u014d gemacht \u2026 Teil 1<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2020\/07\/29\/ich-hab-die-marie-kondo-gemacht-teil-2\/\">Ich hab die Marie Kond\u014d gemacht \u2026 Teil 2<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2020\/07\/30\/ich-hab-die-marie-kondo-gemacht-teil-3\/\">Ich hab die Marie Kond\u014d gemacht \u2026 Teil 3<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2020\/07\/24\/sommer-sonne-boule-kugeln-und-die-grne-fee\/\">Sommer, Sonne, Boule-Kugeln und ein Pastis \u2026<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2021\/04\/29\/29-4-ist-welttag-des-tanzes\/\">29.4. ist Welttag des Tanzes<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2021\/05\/04\/yellow-press-bill-gates-lsst-sich-scheiden-und-andere-katastrophen\/\">Yellow Press: Bill Gates l\u00e4sst sich scheiden und andere Katastrophen<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2021\/04\/26\/gru-aus-dem-karbon-oder-wie-ich-huflattich-fr-brlapp-hielt\/\">Gru\u00df aus dem Karbon, oder wie ich Huflattich f\u00fcr B\u00e4rlapp hielt<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2020\/08\/31\/sommer-sonne-mann-braucht-grill\/\">Sommer, Sonne: Mann braucht Grill \u2026<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2021\/02\/21\/hey-its-barbecue-time-grillsaison-erffnet\/\">Hey, it's Barbecue-Time \u2013 Grillsaison er\u00f6ffnet<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2021\/11\/03\/feigen-geschichten\/\">Feigen-Geschichten \u2026<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2020\/09\/17\/power-napping-ein-schlfchen-in-ehren\/\">Power-Napping: Ein Schl\u00e4fchen in Ehren \u2026<\/a><\/p>\n<p><a href=\"https:\/\/borncity.eu\/senioren\/2020\/08\/27\/foto-projekt-blhender-ackerrandstreifen-teil-i\/\">Foto-Projekt: Bl\u00fchender Ackerrandstreifen<\/a> \u2013 Teil I<br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/?p=13213\">Foto-Projekt: Bl\u00fchender Ackerrandstreifen<\/a> \u2013 Teil II<br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/?p=13223\">Foto-Projekt: Bl\u00fchender Ackerrandstreifen<\/a> \u2013 Teil III<br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2020\/10\/02\/foto-projekt-blhender-ackerrandstreifen-teil-iv\/\">Foto-Projekt: Bl\u00fchender Ackerrandstreifen<\/a> \u2013 Teil IV<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Heute mal wieder eine sehr spezielle Geschichte, die mir in diesem Leben vor vielen, vielen Jahren, genau gesagt, am 12. April 1981, pers\u00f6nlich passiert ist. Ich hatte mich, auf Einladung von guten Freunden, zum Gipfelsturm auf den Wilseder Berg eingefunden. &hellip; <a href=\"https:\/\/borncity.eu\/senioren\/2021\/11\/17\/mein-gipfelsturm-auf-den-wilseder-berg\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,13],"tags":[168,119],"class_list":["post-18044","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-natur","tag-allgemein","tag-natur"],"_links":{"self":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/posts\/18044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/comments?post=18044"}],"version-history":[{"count":1,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/posts\/18044\/revisions"}],"predecessor-version":[{"id":28170,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/posts\/18044\/revisions\/28170"}],"wp:attachment":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/media?parent=18044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/categories?post=18044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/tags?post=18044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}