{"id":18540,"date":"2022-01-14T12:19:26","date_gmt":"2022-01-14T11:19:26","guid":{"rendered":"https:\/\/borncity.com\/senioren\/?p=18540"},"modified":"2022-01-14T12:19:26","modified_gmt":"2022-01-14T11:19:26","slug":"the-ronnetes-sngerin-ronnie-spector-be-my-baby-verstorben","status":"publish","type":"post","link":"https:\/\/borncity.eu\/senioren\/2022\/01\/14\/the-ronnetes-sngerin-ronnie-spector-be-my-baby-verstorben\/","title":{"rendered":"The Ronnetes-S&auml;ngerin Ronnie Spector (Be My Baby) verstorben"},"content":{"rendered":"<p>2019 hatte ich hier im Blog den Artikel <a href=\"https:\/\/borncity.eu\/senioren\/2019\/09\/01\/musik-zum-sonntag-the-ronnetes-be-my-baby\/\">Musik zum Sonntag: The Ronnetes \u2013 Be My Baby<\/a>, in der ich die Gruppe The Ronnetes vorstellte. Die waren in den 60er Jahren mit Titeln wie \"Be My Baby\" und \"Baby, I Love You\" extrem erfolgreich. Am 12. Januar 2022 ist deren S\u00e4ngerin <a href=\"https:\/\/de.wikipedia.org\/wiki\/Ronnie_Spector\" target=\"_blank\" rel=\"noopener\">Ronnie Spector<\/a> (b\u00fcrgerlicher Name Veronica Bennett) im Alter von 78 Jahren an einem Krebsleiden verstorben. Das Redaktionsnetzwerk Deutschland (RND) hat <a href=\"https:\/\/www.rnd.de\/kultur\/ronnie-spector-ist-tot-trauer-um-ronettes-saengerin-mit-be-my-baby-in-die-ruhmeshalle-LJXY3XNWHBBMDJ2D7AGTXIJYYM.html\" target=\"_blank\" rel=\"noopener\">diesen Nachruf<\/a> verfasst. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>2019 hatte ich hier im Blog den Artikel Musik zum Sonntag: The Ronnetes \u2013 Be My Baby, in der ich die Gruppe The Ronnetes vorstellte. Die waren in den 60er Jahren mit Titeln wie \"Be My Baby\" und \"Baby, I &hellip; <a href=\"https:\/\/borncity.eu\/senioren\/2022\/01\/14\/the-ronnetes-sngerin-ronnie-spector-be-my-baby-verstorben\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[168],"class_list":["post-18540","post","type-post","status-publish","format-standard","hentry","category-allgemein","tag-allgemein"],"_links":{"self":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/posts\/18540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/comments?post=18540"}],"version-history":[{"count":0,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/posts\/18540\/revisions"}],"wp:attachment":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/media?parent=18540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/categories?post=18540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/tags?post=18540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}