{"id":1965,"date":"2016-11-27T12:27:20","date_gmt":"2016-11-27T11:27:20","guid":{"rendered":"http:\/\/borncity.com\/senioren\/?p=1965"},"modified":"2020-12-10T08:33:52","modified_gmt":"2020-12-10T07:33:52","slug":"achtung-rckruf-gerucherte-forellenfilets","status":"publish","type":"post","link":"https:\/\/borncity.eu\/senioren\/2016\/11\/27\/achtung-rckruf-gerucherte-forellenfilets\/","title":{"rendered":"Achtung R&uuml;ckruf: Ger&auml;ucherte Forellenfilets"},"content":{"rendered":"<p><img decoding=\"async\" style=\"float: left; margin: 0px 10px 0px 0px; display: inline\" src=\"https:\/\/www.borncity.com\/blog\/wp-content\/uploads\/2015\/01\/Stop.jpg\" align=\"left\">Die <a href=\"http:\/\/www.wechsler.eu\/startseite\/\" target=\"_blank\" rel=\"noopener\">Wechsler Feinfisch GmbH<\/a> aus Erftstadt ruft aus Gr\u00fcnden des Verbraucherschutzes Chargen ger\u00e4ucherter Forellenfilets aus dem Handel zur\u00fcck. Es bestehen gesundheitliche Risiken beim Verzehr des Produktes. <\/p>\n<p><!--more--><\/p>\n<p>Laut des (bei <a href=\"http:\/\/www.lebensmittelwarnung.de\" target=\"_blank\" rel=\"noopener\">www.lebensmittelwarnung.de<\/a> ver\u00f6ffentlichten) R\u00fcckrufs wurden bei mikrobiologischen Untersuchungen Listeria Monocytogenes nachgewiesen. Es bestehen gesundheitliche Risiken beim Verzehr des Produktes. <\/p>\n<p>Die Wechsler Feinfisch GmbH ruft daher ger\u00e4ucherte Forellenfilets 125 g. bis 1.000 gr. Verpackungen, mit den Chargennummern A16298124561 \u2013 A163011245612 mit dem Verbrauchsdatum 27.11.2016 bis 07.12.2016 zur\u00fcck.&nbsp; <\/p>\n<p>Die Verbraucher k\u00f6nnen die Packungen im Handel auch ohne Kassenbon zur\u00fcckgeben. Alle Produkte mit dem Verbrauchsdatum 08.12. und sp\u00e4ter sind nicht betroffen, da der Produktionsfehler zwischenzeitlich lokalisiert und behoben wurde. <\/p>\n<p><strong>\u00c4hnliche Artikel:<br \/><\/strong><a href=\"https:\/\/borncity.eu\/senioren\/2016\/11\/26\/lebensmittel-rgenwalder-ruft-teewurst-zurck\/\">Lebensmittel: R\u00fcgenwalder ruft Teewurst zur\u00fcck<\/a><br \/><a href=\"https:\/\/borncity.eu\/senioren\/2016\/11\/26\/minerall-belasteter-adventskalender-bei-netto\/\">Mineral\u00f6l belasteter Adventskalender bei Netto<\/a><br \/><a href=\"https:\/\/borncity.eu\/senioren\/2016\/11\/25\/schokoladen-kuriositten-weniger-schokogipfel-bei-toblerone-und-einhorn-schokolade-bei-ritter-sport\/\">Schokoladen-Kuriosit\u00e4ten: Weniger Schokogipfel bei Toblerone und Einhorn-Schokolade bei Ritter-Sport<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Wechsler Feinfisch GmbH aus Erftstadt ruft aus Gr\u00fcnden des Verbraucherschutzes Chargen ger\u00e4ucherter Forellenfilets aus dem Handel zur\u00fcck. Es bestehen gesundheitliche Risiken beim Verzehr des Produktes.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[29,310,84],"class_list":["post-1965","post","type-post","status-publish","format-standard","hentry","category-essen","tag-essen","tag-rueckruf","tag-warnung"],"_links":{"self":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/posts\/1965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/comments?post=1965"}],"version-history":[{"count":0,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/posts\/1965\/revisions"}],"wp:attachment":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/media?parent=1965"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/categories?post=1965"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/tags?post=1965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}