{"id":24448,"date":"2024-03-20T00:09:51","date_gmt":"2024-03-19T23:09:51","guid":{"rendered":"https:\/\/borncity.com\/senioren\/?p=24448"},"modified":"2024-03-19T19:31:01","modified_gmt":"2024-03-19T18:31:01","slug":"autokauf-fuer-senioren","status":"publish","type":"post","link":"https:\/\/borncity.eu\/senioren\/2024\/03\/20\/autokauf-fuer-senioren\/","title":{"rendered":"Autokauf f\u00fcr Senioren &#8230;"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" style=\"float: left; margin: 0px 10px 0px 0px; display: inline;\" title=\"VW-K\u00e4fer\" src=\"https:\/\/borncity.eu\/senioren\/wp-content\/uploads\/2023\/05\/FsKkrZe.jpg\" alt=\"VW-K\u00e4fer\" width=\"278\" height=\"176\" \/>Schwieriges Thema: Einerseits der Begriff \"Senioren\", denn \u00c4ltere lassen sich ungern in diese Gruppe einsortieren. Und Autokauf ist auch ein heikles Thema. Aber Hand aufs Herz, \"welches Auto h\u00e4tten's denn gern\" fragte schon Robert Lemke, oder war es ein Schweinerl? Nun ja, es wird schwierig, ein neues Auto mit einem Cockpit wie ein Raumschiff, was man als Senior nicht mehr versteht. Das Thema \"neues Auto\" bzw. Entwicklung auf dem Automobilsektor ist mir die Tage gleich mehrfach untergekommen. Daher packe ich mal ein paar Gedanken in diesen Beitrag.<\/p>\n<p><!--more--><\/p>\n<p>Ich wei\u00df nicht, wie es der Leserschaft geht: Aber beim Gedanken, dass ich ein neue Auto br\u00e4uchte, bin ich gar nicht so gl\u00fccklich. Immer wenn ich mein Fahrzeug zur Werkstatt bringe und dann ein Ersatzfahrzeug aus der neuen Flotte bekommen, stelle ich fest, was die jungen Ingenieurskollegen der K\u00e4uferschar als \"Zwangsbegl\u00fcckung\" spendiert haben. Klar, ich kann das Auto fahren, aber so manche Bedienoption sucht man da dann doch vergeblich.<\/p>\n<h2>Horror neues Auto<\/h2>\n<p>Mit ist noch die Erz\u00e4hlung meiner Frau vor 14 Tagen im Ohr, die vom Sport mit einer Bekannten nach Hause lief. Die Bekannte erz\u00e4hlte, dass deren Sohn mit der Familie in Urlaub wollte, aber der PKW des Sohnes zu klein daf\u00fcr war. Also hat Sohnemann das Auto von Vatter bekommen und Vatter durfte das neueste Daimler-Modell f\u00fcr die \"Tauschzeit\" f\u00fcr die kurzen Fahrten zum B\u00e4cker etc. verwenden. Es sei der reinste Stress gewesen, erz\u00e4hlt die Frau, weil alles digital und per Touchbildschirm zu bedienen sei. Der Mann, ein Computerfreak in der Gruppe 65 Plus sei jedenfalls auch \u00fcberfordert gewesen und die Beiden sehnten sich nach dem R\u00fccktausch der Fahrzeuge.<\/p>\n<p>Fazit dieses Schwanks: Irgendwo ist mein Eindruck, dass die Industrie flei\u00dfig am Bedarf der K\u00e4ufer vorbei entwickelt. Ich \u00e4rgere mich, wenn ich manche Entwicklung so verfolge, die horrende Wartungs- und Reparaturkosten verursacht, und das f\u00fcr Funktionen, die kaum ein Mensch braucht. Und wenn ein solches Bauteil kaputt geht, scheidet der T\u00dcV Auto und K\u00e4ufer.<\/p>\n<p>Ist mir bei einem Renault Laguna passiert &#8211; erst war das \u00c4rgernis, dass der Tausch der Steuerkette alle 50.000 km satte 1.600 Euro kostete, weil dort auch Wasserpumpe und weitere Antriebsriemen im Paket getauscht werden mussten. Und dann fiel das ESP-System aus &#8211; war wirtschaftlich nicht mehr zu reparieren, so dass ich das Auto (das Design habe ich geliebt) zwangsweise vor dem T\u00dcV-Termin an einen K\u00e4ufer in den baltischen Staaten abgeben und ein neues Auto kaufen musste.<\/p>\n<h2>Klatsche durch NCAP-Test 2026<\/h2>\n<p>Es ist eine spannende Geschichte &#8211; denn manchmal frage ich mich, ob \"nur ich so alt und verkn\u00f6chert bin\", weil ich nicht jubilierend auf den neuesten Digitalschei\u00df in modernen Fahrzeugen h\u00fcpfe, sondern den Sinn oft hinterfrage. Aber es gibt nur einige Leute, die die Digitalisierung im Auto. samt Bedienung \u00fcber Touch-Displays, kritisch sehen.<\/p>\n<p>Ich hatte es die Tage dr\u00fcben in meinem IT-Blog im Beitrag\u00a0<a href=\"https:\/\/www.borncity.com\/blog\/2024\/03\/16\/automobile-it-fehlentwicklungen-touchbedienung-als-risiko-datenerfassung-als-falle-fr-besitzer\/\" target=\"_blank\" rel=\"noopener\">Automobile IT-Fehlentwicklungen: Touchbedienung als Risiko; Datenerfassung als Falle f\u00fcr Besitzer<\/a> aufgegriffen. Ab dem Jahr 2026 werden Fahrzeugen im Euro-Raum beim sogenannten NCAP-Test Punkte abgezogen, wenn Bedienelemente nicht mehr am Lenkrad als separate Schalter oder Hebel vorhanden, sondern nur \u00fcber Touch-Bildschirm abrufbar sind.<\/p>\n<p>\"Die \u00fcberm\u00e4\u00dfige Verwendung von Touchscreens ist ein branchenweites Problem, da fast alle Fahrzeughersteller die wichtigsten Bedienelemente auf zentrale Touchscreens verlagern, wodurch die Fahrer gezwungen sind, ihre Augen von der Stra\u00dfe abzuwenden, und das Risiko von Unf\u00e4llen durch Ablenkung steigt\", wird Matthew Avery, Direktor f\u00fcr strategische Entwicklung bei Euro NCAP, zitiert.<\/p>\n<p>\"Die neuen Euro NCAP-Tests, die 2026 anstehen, werden die Hersteller dazu ermutigen, getrennte, physische Bedienelemente f\u00fcr grundlegende Funktionen auf intuitive Weise zu verwenden, um die Zeit, in der die Augen nicht auf der Stra\u00dfe sind, zu begrenzen und somit ein sichereres Fahren zu f\u00f6rdern.\"<\/p>\n<h2>Porsche und VW kippen Modelle wegen Sicherheit<\/h2>\n<p>In der EU gelten ab Juli 2024 neue Regeln f\u00fcr die Cybersicherheit von Automobilen &#8211; wie ich im Blog-Beitrag\u00a0<a href=\"https:\/\/www.borncity.com\/blog\/2024\/03\/19\/mcdonalds-ausfall-ihk-phishing-fujitsu-hack-terracloud-ausfall-und-mehr\/\" target=\"_blank\" rel=\"bookmark noopener\">McDonald's-Ausfall, \"IHK-Phishing\", Fujitsu-Hack, TerraCloud-Ausfall und mehr<\/a> angerissen habe. Hersteller m\u00fcssen bereits bei der Entwicklung der Fahrzeuge nachweisen, dass diese gegen Cyberangriffe abgesichert sind. Bei bestehenden Modellen wird das f\u00fcr mache Hersteller zum Problem, weshalb Porsche die Modelle Macan, Cayman und Boxter aus dem Vertrieb nimmt. Bei VW trifft es \u00a0den Kleinwagen Up sowie den Transporter T6.1.\u00a0 Die Wirtschaftswoche nennt in\u00a0<a href=\"https:\/\/www.wiwo.de\/unternehmen\/auto\/cybersecurity-wegen-neuer-eu-regeln-diese-beliebten-automodelle-werden-eingestellt\/29713422.html\" target=\"_blank\" rel=\"noopener\">diesem Artikel<\/a> noch einige Details.<\/p>\n<h2>Welches Auto kauft man nun?<\/h2>\n<p>Nachdem ich in obigen Zeilen gen\u00fcgend Verunsicherung verbreitet habe, bleibt die Frage: \"Was kauft man nun als \u00e4lterer Mensch f\u00fcr ein Auto?\". Meine Antwort: Ich wei\u00df es definitiv nicht. Elektroauto? Benziner? Kleinwagen? Sportwagen?<\/p>\n<p>An dieser Stelle einfach ein wenig Lesefutter: Das Redaktionsnetzwerk Deutschland (RND) hat die Tage den Beitrag\u00a0<a href=\"https:\/\/www.rnd.de\/mobilitaet\/autokauf-fuer-aeltere-menschen-worauf-zu-achten-ist-NZ4DHUG5INAJTNGWW7XPNKEVLE.html\" target=\"_blank\" rel=\"noopener\">Autokauf f\u00fcr \u00e4ltere Menschen \u2013 worauf zu achten ist<\/a> ver\u00f6ffentlicht. Vielleicht einfach mal\u00a0 durchlesen und schauen, ob man sich in den Kriterien, die der Reporter dort aufgelistet hat, wieder erkennt. Ich habe spontan beschlossen: Solange das vorhandene Auto noch l\u00e4uft, fahre ich es weiter.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Schwieriges Thema: Einerseits der Begriff \"Senioren\", denn \u00c4ltere lassen sich ungern in diese Gruppe einsortieren. Und Autokauf ist auch ein heikles Thema. Aber Hand aufs Herz, \"welches Auto h\u00e4tten's denn gern\" fragte schon Robert Lemke, oder war es ein Schweinerl? &hellip; <a href=\"https:\/\/borncity.eu\/senioren\/2024\/03\/20\/autokauf-fuer-senioren\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[655],"tags":[103],"class_list":["post-24448","post","type-post","status-publish","format-standard","hentry","category-technik","tag-technik"],"_links":{"self":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/posts\/24448","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/comments?post=24448"}],"version-history":[{"count":4,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/posts\/24448\/revisions"}],"predecessor-version":[{"id":24452,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/posts\/24448\/revisions\/24452"}],"wp:attachment":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/media?parent=24448"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/categories?post=24448"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/tags?post=24448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}