{"id":24729,"date":"2024-05-20T00:09:18","date_gmt":"2024-05-19T22:09:18","guid":{"rendered":"https:\/\/borncity.com\/senioren\/?p=24729"},"modified":"2026-05-13T09:28:33","modified_gmt":"2026-05-13T07:28:33","slug":"blue-origin-ns21-mission-6-tourismus-flug-in-den-weltraum-2","status":"publish","type":"post","link":"https:\/\/borncity.eu\/senioren\/2024\/05\/20\/blue-origin-ns21-mission-6-tourismus-flug-in-den-weltraum-2\/","title":{"rendered":"Blue Origin NS25-Mission: 6. Tourismus-Flug in den Weltraum"},"content":{"rendered":"<p>Bereits am Pfingstsonntag, den 19. Mai 2024, fand ein weiterer Touristenflug mit der Mission NS25 (New Shepard) des US-Unternehmen Blue Origin statt. An Bord der Kapsel, die von der New Shepard-Rakete auf eine H\u00f6he von ca. 105 km ins All getragen wurde, befanden sich sechs Personen (Touristen). Ein Passagier war bereits 90 Jahre alt und sollte urspr\u00fcnglich als erster farbiger Astronaut in den sechziger Jahren des vorigen Jahrhundert in den Weltraum starten.<\/p>\n<p><!--more--><\/p>\n<p>Bei diesem Flug waren Mason Angel, Sylvain Chiron, Ed Dwight, Ken Hess, Carol Schaller und Gopi Thotakura an Bord. Nachfolgender <a href=\"https:\/\/xcancel.com\/blueorigin\/status\/1792232014965313990\" target=\"_blank\" rel=\"noopener\">Tweet<\/a> zeigt die Besatzung.<\/p>\n<p><a href=\"https:\/\/borncity.eu\/senioren\/wp-content\/uploads\/2024\/05\/dTES24I.png\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"\" title=\"Blue Origin NS25-Mission 6\" src=\"https:\/\/borncity.eu\/senioren\/wp-content\/uploads\/2024\/05\/dTES24I.png\" alt=\"Blue Origin NS25-Mission\" width=\"595\" height=\"523\" \/><\/a><\/p>\n<p>Auf der Firmenseite lassen sich noch <a href=\"https:\/\/www.blueorigin.com\/news\/ns-25-mission-updates\" target=\"_blank\" rel=\"noopener\">einige Details<\/a> \u00fcber die Passagiere nachlesen. Furore machte bei diesem Flug der Passagier Ed Dwight, der mit 90 Jahren der \u00e4lteste Mensch ist, der bisher an die Grenze zum Weltall geflogen ist. Captain Ed Dwight war ein Kampfpilot der\u00a0Air Force, der 1961 von Pr\u00e4sident John F. Kennedy als erster schwarzer Astronautenkandidat der Nation ausgew\u00e4hlt wurde, aber nie die Gelegenheit zum Flug hatte.\u00a0Die New Shepard hat inzwischen 37 Menschen ins All geflogen, darunter auch die heutige Crew.<\/p>\n<p>Einige Hinweise auf Deutsch gibt es hier sowie in <a href=\"https:\/\/www.heise.de\/news\/Blue-Origin-Erneuter-Startversuch-mit-Besatzung-nach-fast-zwei-Jahren-9723960.html\" target=\"_blank\" rel=\"noopener\">diesem Artikel<\/a>. Dort erf\u00e4hrt man, dass es der erste Flug seit 2022 war, als Blue Origin eine unbemannte New Shepard verloren hat. Ein Video des Flugs findet sich <a href=\"https:\/\/youtu.be\/y0H-I-jMhoA\" target=\"_blank\" rel=\"noopener\">hier <\/a>\u00a0(Start ab 1:22:00). Diese Touristenfl\u00fcge stehen aus Umweltschutzgr\u00fcnden in der Kritik, weil es diese Ausfl\u00fcge nur f\u00fcr Superreiche gibt.<\/p>\n<h2>Blue Origin-Touristenfl\u00fcge ins Weltall<\/h2>\n<p>Amazon-Gr\u00fcnder Jeff Bezos verfolgt mit seiner Raumfahrtfirma Blue Origin das kommerzielle Ziel, Touristen in 100 km H\u00f6he, an die Grenze zu Weltraum zu fliegen und sicher zur Erde zur\u00fcckzukehren. Im Juli 2021 fand der Erstflug mit Jeff Bezos selbst statt (siehe <a href=\"https:\/\/borncity.eu\/senioren\/2021\/07\/20\/heute-will-jeff-bezos-mit-mitstreitern-ins-all-hopsen\/\">Heute will Jeff Bezos mit Mitstreitern ins All hopsen<\/a>). Mit an Bord war damals die 82 j\u00e4hrige Fast-Astronautin Wally Funk (<a href=\"https:\/\/borncity.eu\/senioren\/2021\/07\/02\/wally-funk-fliegt-mit-jeff-bezos-ins-all\/\">Wally Funk fliegt mit Jeff Bezos ins All<\/a>).<\/p>\n<p><img decoding=\"async\" title=\"New Shepard\" src=\"https:\/\/web.archive.org\/web\/20210926232628\/https:\/\/upload.wikimedia.org\/wikipedia\/commons\/thumb\/a\/a9\/Newshepard.jpg\/542px-Newshepard.jpg\" alt=\"New Shepard\" \/><br \/>\nNew Shepard-Landung 2017, Quelle: Wikimedia Bild gemeinfrei<\/p>\n<p>Am 13. Oktober 2021 fand dann der zweite Flug mit Passagieren, der auf 100 km H\u00f6he f\u00fchrt, statt. Bei diesem Flug war der Capitain Kirk-Darsteller William Shutner aus Raumschiff Enterprise dabei. Ein Kurzvideo des Flugs des 90 j\u00e4hrigen Shutners ist im Beitrag <a href=\"https:\/\/borncity.eu\/senioren\/2021\/10\/15\/kurzvideo-des-flugs-von-captain-kirk-an-die-grenze-des-weltraums\/\">Kurzvideo des Flugs von Captain Kirk an die Grenze des Weltraums<\/a> zu sehen. Beim dritten Flug am 11. Dezember 2021 wurden erstmals sechs Passagiere mit der New Shepard-Rakete an die Grenze des Weltalls transportiert und konnten sicher landen (siehe <a href=\"https:\/\/borncity.eu\/senioren\/2021\/12\/21\/blue-origin-gelingt-dritter-weltraumhopser-ns-19-mit-6-personen\/\">Blue Origin gelingt dritter Weltraumhopser (NS-19) mit 6 Personen<\/a>). Mit an Bord war Laura Shepard Churchley, die Tochter des ersten Amerikaners im All, n\u00e4mlich Alan Shepard.<\/p>\n<p><strong>\u00c4hnliche Artikel:<\/strong><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2021\/04\/17\/blue-origin-erfolgreicher-testflug-in-den-weltraum\/\">Blue Origin: Erfolgreicher Testflug in den Weltraum<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2019\/05\/04\/blue-origin-startet-erneut-raumflug\/\">Blue Origin startet erfolgreich erneut Test-Raumflug<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2018\/07\/19\/testflug-der-touristenrakete-new-shepard\/\">Testflug der Touristenrakete New Shepard<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2021\/06\/09\/amazon-grnder-fliegt-am-20-7-2021-mit-blue-origin-ins-all\/\">Amazon-Gr\u00fcnder fliegt am 20.7.2021 mit Blue Origin ins All<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2021\/07\/02\/wally-funk-fliegt-mit-jeff-bezos-ins-all\/\">Wally Funk fliegt mit Jeff Bezos ins All<\/a><strong><br \/>\n<\/strong><a href=\"https:\/\/borncity.eu\/senioren\/2019\/10\/23\/blue-origin-will-bis-25-mit-artemis-menschen-auf-den-mond\/\">Blue Origin will bis 2025 mit Menschen auf den Mond<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2021\/07\/03\/rattenrennen-der-reichen-richard-branson-will-am-11-juli-2021-ins-all-fliegen\/\">Weltallrennen der Reichen? Richard Branson will am 11. Juli 2021 ins All fliegen<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2021\/07\/20\/heute-will-jeff-bezos-mit-mitstreitern-ins-all-hopsen\/\">Heute will Jeff Bezos mit Mitstreitern ins All hopsen<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2021\/07\/26\/gemein-keine-astronauten-schwingen-fr-jeff-bezos-co\/\">Gemein: Keine Astronauten-Schwingen f\u00fcr Jeff Bezos &amp; Co.<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2021\/07\/25\/weltraum-hopser-teen-meint-jeff-ich-habe-noch-nie-bei-dir-auf-amazon-eingekauft\/\">Weltraum-Hopser: Teen meint \"Jeff, ich habe noch nie bei dir auf Amazon eingekauft\"<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2021\/08\/16\/amazon-kunden-stinkig-ber-jeff-bezos-weltraumhopser\/\">Amazon-Kunden \"stinkig\" \u00fcber Jeff Bezos Weltraumhopser \u2026<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2021\/10\/09\/william-shatner-capitain-kirk-soll-mit-90-jahren-noch-mit-ins-all\/\">William Shatner, Captain Kirk, soll mit 90 Jahren mit ins All<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2021\/10\/13\/captain-kirk-vor-dem-weltraumhopser-13-10-2021\/\">Captain Kirk vor dem Weltraumhopser (13.10.2021)<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2021\/10\/15\/kurzvideo-des-flugs-von-captain-kirk-an-die-grenze-des-weltraums\/\">Kurzvideo des Flugs von Captain Kirk an die Grenze des Weltraums<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2021\/11\/13\/glen-de-vries-stirbt-bei-flugzeugabsturz\/\">Glen de Vries stirbt bei Flugzeugabsturz<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2021\/10\/25\/spacex-privater-weltraum-trip-fllt-mangels-kundschaft-aus\/\">SpaceX: Privater Weltraum-Trip f\u00e4llt mangels Kundschaft aus<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2021\/11\/26\/blue-origin-3-flug-am-9-dez-2021-mit-astronauten-tochter-und-us-moderator\/\">Blue Origin: 3. Flug am 9. Dez. 2021 mit Astronauten-Tochter und US-Moderator<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2021\/12\/21\/blue-origin-gelingt-dritter-weltraumhopser-ns-19-mit-6-personen\/\">Blue Origin gelingt dritter Weltraumhopser (NS-19) mit 6 Personen<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2022\/02\/21\/blue-origin-will-2022-mit-dem-weltraumtourismus-durchstarten-doppelte-zahl-an-passagieren\/\">Blue Origin will 2022 mit dem Weltraumtourismus durchstarten, doppelte Zahl an Passagieren<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2022\/04\/01\/blue-origin-hat-4-tourismus-flug-in-den-weltraum-geschafft\/\">Blue Origin hat 4. Tourismus-Flug in den Weltraum geschafft<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2022\/06\/06\/blue-origin-ns21-mission-5-tourismus-flug-in-den-weltraum-geschafft\/\">Blue Origin NS21-Mission: 5. Tourismus-Flug in den Weltraum geschafft<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bereits am Pfingstsonntag, den 19. Mai 2024, fand ein weiterer Touristenflug mit der Mission NS25 (New Shepard) des US-Unternehmen Blue Origin statt. An Bord der Kapsel, die von der New Shepard-Rakete auf eine H\u00f6he von ca. 105 km ins All &hellip; <a href=\"https:\/\/borncity.eu\/senioren\/2024\/05\/20\/blue-origin-ns21-mission-6-tourismus-flug-in-den-weltraum-2\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[655],"tags":[103],"class_list":["post-24729","post","type-post","status-publish","format-standard","hentry","category-technik","tag-technik"],"_links":{"self":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/posts\/24729","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/comments?post=24729"}],"version-history":[{"count":7,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/posts\/24729\/revisions"}],"predecessor-version":[{"id":29868,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/posts\/24729\/revisions\/29868"}],"wp:attachment":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/media?parent=24729"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/categories?post=24729"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/tags?post=24729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}