{"id":3154,"date":"2017-06-03T01:47:00","date_gmt":"2017-06-02T23:47:00","guid":{"rendered":"http:\/\/borncity.com\/senioren\/?p=3154"},"modified":"2017-05-29T17:44:30","modified_gmt":"2017-05-29T15:44:30","slug":"rote-karte-fr-putzmuffel-was-ist-mit-putzteufeln","status":"publish","type":"post","link":"https:\/\/borncity.eu\/senioren\/2017\/06\/03\/rote-karte-fr-putzmuffel-was-ist-mit-putzteufeln\/","title":{"rendered":"Rote Karte f&uuml;r Putzmuffel"},"content":{"rendered":"<p>Heute noch ein Beitrag zu einem etwas leidigeren Thema in Beziehungen. Wer \u00fcbernimmt die Hausarbeit und wie gr\u00fcndlich wird geputzt. Dank einer von Forsa im Auftrag der Firma Leifheit durchgef\u00fchrten Studie wissen wir nun genauer, was so mancher l\u00e4ngst geahnt hat.<\/p>\n<p><!--more--><\/p>\n<p>Kurz zusammen gefasst: 78% der 18- bis 45-J\u00e4hrigen streiten sich \u00fcber die Hausarbeit.\u00a0 Am h\u00e4ufigsten gestritten wird, weil sich einer der Partner vor der Hausarbeit dr\u00fcckt (35%) und weil die Ergebnisse zu schwach sind (30%). Zwei Drittel der Befragten sagen, dass eine mangelnde Unterst\u00fctzung bei der Hausarbeit sogar die Beziehung belasten w\u00fcrde. Und bei fast jedem Sechsten w\u00fcrde die Dr\u00fcckeberger-Mentalit\u00e4t des Partners sogar Grund sein, ihm die \u201eRote Karte\" zu zeigen und sich von ihm zu trennen.<\/p>\n<h2>Zielvorgaben nicht eingehalten<\/h2>\n<p>Streit \u00fcber die Hausarbeit gibt es in fast jeder Beziehung. Nur jeder f\u00fcnfte der Befragten kommt ohne Streit aus. Neben dem Dr\u00fcckeberger-Syndrom und den schwachen Ergebnissen gibt es eine Reihe weiterer Gr\u00fcnde f\u00fcr den Beziehungsstress: Weil nicht oft genug geputzt wird (24%), fehlende Gr\u00fcndlichkeit beim Putzen (16%), weil sich der Partner nicht an die Anweisungen h\u00e4lt (12%) oder nur die angenehmen Aufgaben \u00fcbernimmt (11%).<\/p>\n<h2>Anforderungen an den Partner<\/h2>\n<p>Harmonie, Verl\u00e4sslichkeit und Hilfe im Alltag scheint den befragten Deutschen in einer Beziehung sehr wichtig. So erwarten von den Befragten nur 18% der M\u00e4nner und 36% der Frauen von einem potentiellen Partner eine gute \u201efinanzielle Ausstattung\". Praktische F\u00e4higkeiten sind hingegen gefragt: 42% der Frauen w\u00fcnschen sich handwerkliche Kenntnisse vom Mann und 75% wissen es zu sch\u00e4tzen, wenn er sie bei der Hausarbeit unterst\u00fctzt.<\/p>\n<p>Wunsch und Wirklichkeit unterschieden sich im Haushalt elementar: Zwar ist die Mehrheit der Befragten (88%) f\u00fcr eine gerechte Aufgabenverteilung. Die Wirklichkeit sieht aber anders aus: Nur bei jedem Zweiten ist die Hausarbeit fair verteilt. 57% der Frauen sagen, dass sie selbst ausschlie\u00dflich oder \u00fcberwiegend die Hausarbeit machen. Die Frauen sind hiermit allerdings nicht ungl\u00fccklich. 75% sind mit ihren Aufgaben im Haushalt mehr oder weniger zufrieden. 38% der befragten Frauen sind sogar au\u00dferordentlich oder sehr zufrieden. Jede Vierte w\u00fcrde sich allerdings eine andere Aufgabenverteilung w\u00fcnschen.<\/p>\n<h2>M\u00e4nner f\u00fcrs Grobe, Frauen sind Allesk\u00f6nner<\/h2>\n<p>Die Frauen beauftragen ihre M\u00e4nner eher mit den groben Dingen der Hausarbeit. Typische M\u00e4nneraufgaben sind aus Sicht der befragten Frauen den M\u00fcll rauszubringen (77%), staubzusaugen (56%) und Geschirr zu sp\u00fclen (55%). Wenig Vertrauen hat das weibliche Geschlecht in die F\u00e4higkeiten ihrer Partner beim Fensterputzen, B\u00fcgeln und W\u00e4sche\u00adwaschen. Hier ist nur jede Vierte der Meinung, dass ihr Mann diese Aufgabe gut erf\u00fcllen kann.<\/p>\n<h2>Kann Putzen Spa\u00df machen?<\/h2>\n<p>Hausarbeit ist laut der Studie gar nicht so schlimm. Nur wenige T\u00e4tigkeiten werden als sehr unangenehm empfunden. Am unbeliebtesten sind die Reinigung der Toilette und der Fensterputz. Nur 14% der Befragten k\u00f6nnen sich daf\u00fcr begeistern. Auch Staubwischen und den Fu\u00dfboden zu wischen ist gerade einmal bei jedem F\u00fcnften beliebt.<\/p>\n<p>Die klare Nummer eins in Sachen Spa\u00dffaktor ist das Kochen. Zwei Drittel aller Befragten kochen mit gro\u00dfer Begeisterung. Dies k\u00f6nnte darauf zur\u00fcckzuf\u00fchren sein, dass beim Kochen Paare kreativ sein k\u00f6nnen und sich hinterher selbst belohnen. Das Kochen und Essen kann auch gut f\u00fcr die Beziehung sein, denn die Partner verbringen gemeinsam Zeit und k\u00f6nnen sich dabei unterhalten und Spa\u00df haben.<\/p>\n<h2>Freiwilliger \u201eDienst\" f\u00fcr Bonuspunkte<\/h2>\n<p>Gute Nachricht f\u00fcr das m\u00e4nnliche Geschlecht: Wer sich unaufgefordert im Haushalt engagiert, sammelt bei seiner Partnerin Extrapunkte. Die befragten Frauen interpretieren einen solchen Einsatz als Liebesbeweis. 51% der Frauen bezeichnen einen solchen Partner als zuverl\u00e4ssig, 55% als r\u00fccksichtsvoll und 40% sagen, dass der Partner ihnen damit beweist, dass sie ihm wichtig ist. Jede vierte der Frauen gesteht einem solchen \u201eHausmann\" sogar Traummann-Potenzial zu.<\/p>\n<p>Andererseits sind viele Frauen auch pragmatisch eingestellt: Es gilt 'Wenigstens, der Mann hilft \u00fcberhaupt im Haushalt'. Frauen denken l\u00f6sungsorientiert: 67% der befragten Frauen geben ihren M\u00e4nnern Aufgaben, die sie gut k\u00f6nnen.<\/p>\n<p>Eine l\u00e4ngerfristige Verweigerung bei der Hausarbeit kann die Beziehung stark belasten. 65% der Befragten best\u00e4tigen dies und 15% w\u00fcrden sich wahrscheinlich sogar von ihrem Partner trennen. Immerhin 30% vermuten, dass sich eine Verweigerungshaltung im Haushalt nicht negativ auf ihre Beziehung auswirken w\u00fcrde. Generell scheinen die meisten Beziehungen der Befragten intakt \u2013 denn 75% sind mit ihrer Partnerschaft sehr gl\u00fccklich.<\/p>\n<p>Die Ergebnisse der gesamten Studie sind verf\u00fcgbar unter <a href=\"http:\/\/www.leifheit.de\" target=\"_blank\" rel=\"noopener noreferrer\">www.leifheit.de<\/a>. Bleibt abschlie\u00dfend noch die Frage: Wie wirkt sich \u00fcberzogene Putzsucht (der Putzteufel) auf die Partnerschaft aus? Wenn Mann an der Wohnungst\u00fcr die Pantoffel \u00fcberziehen muss und sich nicht aufs Sofa l\u00fcmmeln darf, weil sonst die Fransen der Schmuckkissen unordentlich werden? Auf diese spannende Frage gibt die Leifheit-Befragung leider keine Antwort \u2013 denn zum 'Fransen-Ausrichten' hat man kein Ger\u00e4t.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Heute noch ein Beitrag zu einem etwas leidigeren Thema in Beziehungen. Wer \u00fcbernimmt die Hausarbeit und wie gr\u00fcndlich wird geputzt. Dank einer von Forsa im Auftrag der Firma Leifheit durchgef\u00fchrten Studie wissen wir nun genauer, was so mancher l\u00e4ngst geahnt &hellip; <a href=\"https:\/\/borncity.eu\/senioren\/2017\/06\/03\/rote-karte-fr-putzmuffel-was-ist-mit-putzteufeln\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[168],"class_list":["post-3154","post","type-post","status-publish","format-standard","hentry","category-allgemein","tag-allgemein"],"_links":{"self":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/posts\/3154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/comments?post=3154"}],"version-history":[{"count":0,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/posts\/3154\/revisions"}],"wp:attachment":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/media?parent=3154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/categories?post=3154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/tags?post=3154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}