{"id":3883,"date":"2017-09-08T01:00:00","date_gmt":"2017-09-07T23:00:00","guid":{"rendered":"http:\/\/borncity.com\/senioren\/?p=3883"},"modified":"2022-04-22T07:58:22","modified_gmt":"2022-04-22T05:58:22","slug":"demenz-jeder-3-fall-vermeidbar","status":"publish","type":"post","link":"https:\/\/borncity.eu\/senioren\/2017\/09\/08\/demenz-jeder-3-fall-vermeidbar\/","title":{"rendered":"Demenz: Jeder 3. Fall vermeidbar"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" style=\"float: left; margin: 0px 10px 0px 0px; display: inline;\" title=\"Gesundheit\" src=\"http:\/\/www.borncity.com\/blog\/wp-content\/uploads\/2016\/06\/Gesundheit-2.jpg\" alt=\"Gesundheit\" width=\"60\" height=\"56\" align=\"left\" border=\"0\" \/>Viele Menschen erkranken in h\u00f6herem Alter an Demenz. Jetzt kommen Fachleute zur Erkenntnis, dass ein Drittel der Demenzf\u00e4lle durch \u00c4nderung des Lebensstils vermeidbar sei.<\/p>\n<p><!--more--><\/p>\n<p>Demenz ist ein Oberbegriff f\u00fcr viele Krankheitsbilder, die mit sinkender Hirnleistung einhergehen (siehe <a href=\"https:\/\/de.wikipedia.org\/wiki\/Demenz\">Wikipedia<\/a> und <a href=\"https:\/\/web.archive.org\/web\/20191230181926\/http:\/\/www.alzheimerinfo.de:80\/alzheimer\/demenz_alzheimer\/index.jsp\">Alzheimerinfo<\/a>). Die Zahl der Neuerkrankungen an Demenz liegt in Deutschland bei 300.000 F\u00e4llen pro Jahr. Da w\u00e4re es hilfreich, Ans\u00e4tze zu kennen, um die Erkrankung pr\u00e4ventiv zu vermeiden.<\/p>\n<p>Im Blog-Beitrag <a href=\"https:\/\/borncity.eu\/senioren\/?p=3879\">Drei Faktoren bestimmen Alzheimer-Demenz-Risiko<\/a> hatte ich Informationen zu einer speziellen Krankheitsform, der Alzheimer-Demenz, zusammen getragen. In einem Abschnitt ging es auch um die Erkenntnis, dass sich die Folgen einer Alzheimer-Erkrankung im Fr\u00fchstadium durch \u00c4nderung des Lebensstils und entsprechender Therapie aufhalten und sogar lindern lassen. Eine finnische Studie ergab ebenfalls, dass Training, Ern\u00e4hrung und Denksport den Folgen entgegen wirken kann (siehe <a href=\"https:\/\/borncity.eu\/senioren\/?p=3885\">Training hilft wohl gegen Alzheimer-Demenz<\/a>).<\/p>\n<h2>Demenz-Pr\u00e4vention soll helfen<\/h2>\n<p>Eine bei Science Direct in der Onlineausgabe von The Lancet <a href=\"https:\/\/web.archive.org\/web\/20191224194229\/https:\/\/www.sciencedirect.com\/science\/article\/pii\/S0140673617313636\" target=\"_blank\" rel=\"noopener noreferrer\">vorgestellte Studie<\/a> (Englisch, kostenpflichtig) kommt jetzt zum Schluss, dass jeder Dritte Demenzfall durch Pr\u00e4vention vermeidbar sei. Eine Gruppe von 24 Fachleuten sichtete die Forschung \u00fcber Pr\u00e4ventions- und Behandlungsans\u00e4tze f\u00fcr Demenz. Dabei hat man hat neun Risikofaktoren f\u00fcr Demenzerkrankungen identifiziert. Schl\u00fcssel seien:<\/p>\n<ul>\n<li>Bildung in der Jugend,<\/li>\n<li>Die Behandlung von Bluthochdruck<\/li>\n<li>Das Vermeiden von \u00dcbergewicht<\/li>\n<li>Die Bek\u00e4mpfung von Schwerh\u00f6rigkeit<\/li>\n<\/ul>\n<p>Alleine mit diesen Ma\u00dfnahmen lie\u00dfen sich 20 Prozent der Demenzf\u00e4lle im Alter schlicht und einfach verhindern. Im h\u00f6heren Alter k\u00f6nnten weitere 15 Prozent der Demenzf\u00e4lle verhindert werden, wenn man<\/p>\n<ul>\n<li>Ma\u00dfnahmen gegen Depression,<\/li>\n<li>Behandlung von Diabetes<\/li>\n<li>und gegen die Einsamkeit vorgeht<\/li>\n<\/ul>\n<p>Hinzu kommen regelm\u00e4\u00dfig Bewegungen und der Verzicht auf Rauchen, was wohl ebenfalls ein wichtiger Risikofaktor ist. Da diese mit dem Lebensstil und der medizinischen Versorgung zusammenh\u00e4ngen, sollte eine Pr\u00e4vention erheblich mehr als die Behandlung mit Anti-Dementiva bringen, so die Fachleute. Ein deutschsprachiger Artikel mit einer Zusammenfassung findet sich in <a title=\"http:\/\/www.spektrum.de\/news\/fachleute-ein-drittel-aller-demenzfaelle-ist-vermeidbar\/1484353\" href=\"http:\/\/www.spektrum.de\/news\/fachleute-ein-drittel-aller-demenzfaelle-ist-vermeidbar\/1484353\" target=\"_blank\" rel=\"noopener noreferrer\">spektrum.de<\/a>.<\/p>\n<p><strong>\u00c4hnliche Artikel:<br \/>\n<\/strong><a href=\"https:\/\/borncity.eu\/senioren\/?p=3879\">Drei Faktoren bestimmen Alzheimer-Demenz-Risiko<br \/>\n<\/a><a href=\"https:\/\/borncity.eu\/senioren\/?p=3885\">Training hilft wohl gegen Alzheimer-Demenz<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2017\/09\/08\/demenz-jeder-3-fall-vermeidbar\/\" rel=\"bookmark\">Demenz: Jeder 3. Fall vermeidbar<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2017\/09\/09\/wirkt-curry-alzheimerprvention\/\" rel=\"bookmark\">Wirkt Curry als Alzheimerpr\u00e4vention?<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2017\/02\/13\/hrminderung-und-demenzrisiko\/\">H\u00f6rminderung und Demenzrisiko<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2017\/02\/20\/eine-app-soll-den-hrsinn-wieder-schrfen\/\">Eine App soll den H\u00f6rsinn wieder sch\u00e4rfen<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2016\/09\/09\/stress-lsst-uns-das-schneller-altern\/\">Stress: L\u00e4sst uns das schneller altern?<\/a><br \/>\n<a href=\"https:\/\/borncity.eu\/senioren\/2016\/03\/16\/krankenhaustrauma-bedroht-ltere-patienten\/\">Krankenhaustrauma bedroht \u00e4ltere Patienten<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Viele Menschen erkranken in h\u00f6herem Alter an Demenz. Jetzt kommen Fachleute zur Erkenntnis, dass ein Drittel der Demenzf\u00e4lle durch \u00c4nderung des Lebensstils vermeidbar sei.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[32],"tags":[83],"class_list":["post-3883","post","type-post","status-publish","format-standard","hentry","category-gesundheit","tag-gesundheit"],"_links":{"self":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/posts\/3883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/comments?post=3883"}],"version-history":[{"count":0,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/posts\/3883\/revisions"}],"wp:attachment":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/media?parent=3883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/categories?post=3883"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/tags?post=3883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}