{"id":9289,"date":"2019-05-31T00:02:00","date_gmt":"2019-05-30T22:02:00","guid":{"rendered":"https:\/\/borncity.com\/senioren\/?p=9289"},"modified":"2024-10-01T14:54:17","modified_gmt":"2024-10-01T12:54:17","slug":"frhjahrsputz-auf-der-internationalen-raumstation-iss","status":"publish","type":"post","link":"https:\/\/borncity.eu\/senioren\/2019\/05\/31\/frhjahrsputz-auf-der-internationalen-raumstation-iss\/","title":{"rendered":"Fr&uuml;hjahrsputz auf der internationalen Raumstation ISS"},"content":{"rendered":"<p>Auch im Weltall ist man vom Putzen nicht wirklich befreit. Die Astronauten, die sich auf der internationalen Raumstation (ISS) aufhalten, m\u00fcssen auch 'Putzdienste' \u00fcbernehmen. Die Woche sogar im Au\u00dfenbereich der Station.<\/p>\n<p><!--more--><\/p>\n<p>Kommandeur Oleg Kononenko und sein Kollege Alexej Owtschinin absolvierten in der Nacht zum Donnerstag, vom 29. auf den 30. Mai 2019, einen sechsst\u00fcndigen Au\u00dfeneinsatz. <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" title=\"Oleg Kononenko und Alexej Owtschinin auf der ISS\" alt=\"Oleg Kononenko und Alexej Owtschinin auf der ISS\" src=\"https:\/\/web.archive.org\/web\/20190828032025\/https:\/\/www.roscosmos.ru\/media\/files\/leonovvkd.jpg\" width=\"641\" height=\"361\"><\/p>\n<p>Die Roskosmos-Astronauten Oleg Kononenko (links) und Alexei Ovchininin (rechts)<\/p>\n<p>Das obige Foto von der <a href=\"https:\/\/web.archive.org\/web\/20220113103134\/https:\/\/www.roscosmos.ru\/26384\/\" target=\"_blank\" rel=\"noopener noreferrer\">Roskomos-Seite<\/a> zeigt die beiden Kosmonauten im Bereich, wo die Raumanz\u00fcge angelegt werden. Nachfolgendes Video zeigt einen Ausschnitt der Au\u00dfenarbeiten, die Wartungsaufgaben wie das Entnehmen von Proben, die wieder zur Erde sollen, oder der Austausch von Instrumenten umfassten. <\/p>\n<blockquote class=\"twitter-tweet\" data-lang=\"de\">\n<p lang=\"en\" dir=\"ltr\">Russian cosmonauts Oleg Kononenko and Alexey Ovchinin ventured outside the ISS to 'retrieve science experiments and conduct maintenance on the orbiting laboratory,' according to NASA <a href=\"https:\/\/t.co\/yfnIRHH4B2\">pic.twitter.com\/yfnIRHH4B2<\/a><\/p>\n<p>\u2014 Reuters Top News (@Reuters) <a href=\"https:\/\/twitter.com\/Reuters\/status\/1133942361023754240?ref_src=twsrc%5Etfw\">30. Mai 2019<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script> <\/p>\n<p>Dabei kann auch mal was schief gehen und irgend etwas entschwindet ins Weltall, wie der folgende Clip zeigt. <\/p>\n<blockquote class=\"twitter-tweet\" data-lang=\"de\">\n<p lang=\"en\" dir=\"ltr\">Busy day on <a href=\"https:\/\/twitter.com\/Space_Station?ref_src=twsrc%5Etfw\">@Space_Station<\/a> as cosmonauts Oleg Kononenko and Alexey Ovchinin retrieved science experiments &amp; conducted <a href=\"https:\/\/twitter.com\/hashtag\/ISS?src=hash&amp;ref_src=twsrc%5Etfw\">#ISS<\/a> maintenance during a six-hour spacewalk. <a href=\"https:\/\/t.co\/g51Vnk0OJ4\">pic.twitter.com\/g51Vnk0OJ4<\/a><\/p>\n<p>\u2014 Heather D. Smith  (@TheHeathernaut) <a href=\"https:\/\/twitter.com\/TheHeathernaut\/status\/1133944840478216192?ref_src=twsrc%5Etfw\">30. Mai 2019<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script> <\/p>\n<p>Zu den Aufgaben der beiden M\u00e4nner geh\u00f6rte auch, die Au\u00dfenscheiben der ISS-Module zu reinigen. Die Kollegen bei heise habe <a href=\"https:\/\/www.heise.de\/newsticker\/meldung\/Fruehjahrsputz-im-Weltall-Zwei-Kosmonauten-reinigen-ISS-von-aussen-4435595.html\" target=\"_blank\" rel=\"noopener noreferrer\">diesen Beitrag<\/a> zum Au\u00dfeneinsatz ver\u00f6ffentlicht. <\/p>\n<h2>Erster Spazierg\u00e4nger im All wurde 85<\/h2>\n<p>Den Au\u00dfeneinsatz widmeten die Astronauten dem ersten Menschen, der einen Au\u00dfenbordeinsatz im All (als 'Weltraumspaziergang' bezeichnet) unternahm. Am 18. M\u00e4rz 1965 stieg der russische Kosmonaut <a href=\"https:\/\/de.wikipedia.org\/wiki\/Alexei_Archipowitsch_Leonow\" target=\"_blank\" rel=\"noopener noreferrer\">Alexej Archipowitsch Leonow<\/a> aus dem Raumschiff \"Woschod-2\" zum ersten Au\u00dfeneinsatz der Menschheit aus. <\/p>\n<blockquote class=\"twitter-tweet\" data-lang=\"de\">\n<p lang=\"en\" dir=\"ltr\">The first <a href=\"https:\/\/twitter.com\/hashtag\/SPACEWALKER?src=hash&amp;ref_src=twsrc%5Etfw\">#SPACEWALKER<\/a> Alexei Leonov turns 85. Watch cosmonauts at <a href=\"https:\/\/twitter.com\/hashtag\/ISS?src=hash&amp;ref_src=twsrc%5Etfw\">#ISS<\/a> pay tribute to the pioneer and footage from the historic first steps into space. <a href=\"https:\/\/twitter.com\/hashtag\/NASA?src=hash&amp;ref_src=twsrc%5Etfw\">#NASA<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/ESO?src=hash&amp;ref_src=twsrc%5Etfw\">#ESO<\/a> <a href=\"https:\/\/twitter.com\/Space_Station?ref_src=twsrc%5Etfw\">@Space_Station<\/a> <a href=\"https:\/\/twitter.com\/roscosmos?ref_src=twsrc%5Etfw\">@Roscosmos<\/a> <a href=\"https:\/\/t.co\/W95oQDXWfH\">pic.twitter.com\/W95oQDXWfH<\/a><\/p>\n<p>\u2014 CGTN America (@cgtnamerica) <a href=\"https:\/\/twitter.com\/cgtnamerica\/status\/1134140983552159747?ref_src=twsrc%5Etfw\">30. Mai 2019<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>  <\/p>\n<p>Das Video in obigem Tweet zeigt, wie die ISS-Astronauten ein Foto von Leonow zeigen. Weiterhin werden Videobilder vom damaligen Au\u00dfeneinsatz mit eingeblendet. Leonow konnte am gestrigen Donnerstag seinen 85. Geburtstag feiern.<\/p>\n<p><strong>\u00c4hnliche Artikel<\/strong><br \/><a href=\"https:\/\/borncity.eu\/senioren\/2018\/11\/20\/jubilum-20-jahre-internationale-raumstation-iss\/\">Jubil\u00e4um: 20 Jahre internationale Raumstation ISS<\/a><br \/><a href=\"https:\/\/borncity.eu\/senioren\/2017\/12\/06\/pizza-backen-auf-der-iss\/\">Pizza backen auf der ISS<\/a><br \/><a href=\"https:\/\/borncity.eu\/senioren\/2018\/12\/18\/start-eines-soyus-raumschiffs-von-der-iss-gefilmt\/\">Start eines Soyus-Raumschiffs von der ISS gefilmt<\/a><br \/><a href=\"https:\/\/borncity.eu\/senioren\/2018\/11\/25\/start-des-raumtransporters-gefilmt-von-der-iss\/\">Start des Raumtransporters, gefilmt von der ISS<\/a><br \/>Google Street View: Blick in die Internationale Raumstation<br \/><a href=\"https:\/\/borncity.eu\/senioren\/2016\/09\/11\/wo-ist-was-auf-der-internationalen-raumstation\/\">Wo ist was auf der Internationalen Raumstation<\/a><br \/><a href=\"https:\/\/borncity.eu\/senioren\/2017\/12\/02\/astronaut-filmt-seinen-weltraumspaziergang\/\">Astronaut filmt seinen Weltraumspaziergang<\/a><br \/><a href=\"https:\/\/borncity.eu\/senioren\/2018\/10\/14\/flug-zur-raumstation-kurz-oder-lang\/\">Flug zur Raumstation: Kurz oder lang?<\/a><br \/><a href=\"https:\/\/borncity.eu\/senioren\/2018\/09\/05\/weltraum-krimi-leck-in-der-internationalen-raumstation\/\">Weltraum-Krimi: Das Leck in der internationalen Raumstation<\/a><br \/><a href=\"https:\/\/borncity.eu\/senioren\/2017\/11\/15\/langzeit-raumfahrtmissionen-wirken-sich-auf-das-gehirn-aus\/\">Langzeit-Raumfahrtmissionen wirken sich auf das Gehirn aus<\/a><br \/><a href=\"https:\/\/borncity.eu\/senioren\/2017\/10\/31\/raumfahrt-gehversuche-nach-340-tagen-im-all\/\">Raumfahrt: Gehversuche nach 340 Tagen im All<br \/><\/a><a href=\"https:\/\/web.archive.org\/web\/20240424055927\/https:\/\/borncity.eu\/senioren\/2017\/10\/08\/360-grad-video-eines-weltraumspaziergangs\/\">360-Grad-Video eines Weltraumspaziergangs<\/a><br \/><a href=\"https:\/\/borncity.eu\/senioren\/2019\/04\/15\/mikroben-im-all-iss-voller-keime\/\">Mikroben im All, ISS voller Keime<\/a><br \/><a href=\"https:\/\/borncity.eu\/senioren\/2019\/05\/28\/vor-60-jahren-miss-able-und-miss-baker-zum-weltraumhopser\/\">Vor 60 Jahren: Miss Able und Miss Baker zum Weltraumhopser<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Auch im Weltall ist man vom Putzen nicht wirklich befreit. Die Astronauten, die sich auf der internationalen Raumstation (ISS) aufhalten, m\u00fcssen auch 'Putzdienste' \u00fcbernehmen. Die Woche sogar im Au\u00dfenbereich der Station.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[655],"tags":[222],"class_list":["post-9289","post","type-post","status-publish","format-standard","hentry","category-technik","tag-raumfahrt"],"_links":{"self":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/posts\/9289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/comments?post=9289"}],"version-history":[{"count":3,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/posts\/9289\/revisions"}],"predecessor-version":[{"id":26589,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/posts\/9289\/revisions\/26589"}],"wp:attachment":[{"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/media?parent=9289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/categories?post=9289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/borncity.eu\/senioren\/wp-json\/wp\/v2\/tags?post=9289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}